{"id":3272,"date":"2021-06-25T13:06:55","date_gmt":"2021-06-25T13:06:55","guid":{"rendered":"https:\/\/www.bonitastay.com\/home\/"},"modified":"2026-04-13T10:27:49","modified_gmt":"2026-04-13T10:27:49","slug":"home","status":"publish","type":"page","link":"https:\/\/www.bonitastay.com\/en\/","title":{"rendered":"Home"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"3272\" class=\"elementor elementor-3272 elementor-634\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-8f3300e elementor-section-boxed elementor-section-height-default elementor-section-height-default parallax_section_no qode_elementor_container_no\" data-id=\"8f3300e\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-4be36f5\" data-id=\"4be36f5\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f87c91b elementor-widget elementor-widget-slider_revolution\" data-id=\"f87c91b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"slider_revolution.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\r\n\t\t<div class=\"wp-block-themepunch-revslider\">\n\t\t\t<!-- START home REVOLUTION SLIDER 6.6.12 --><p class=\"rs-p-wp-fix\"><\/p>\n\t\t\t<rs-module-wrap id=\"rev_slider_1_1_wrapper\" data-source=\"gallery\" style=\"visibility:hidden;background:transparent;padding:0;margin:0px auto;margin-top:0;margin-bottom:0;\">\n\t\t\t\t<rs-module id=\"rev_slider_1_1\" style=\"\" data-version=\"6.6.12\">\n\t\t\t\t\t<rs-slides style=\"overflow: hidden; position: absolute;\">\n\t\t\t\t\t\t<rs-slide style=\"position: absolute;\" data-key=\"rs-1\" data-title=\"Slide\" data-thumb=\"\/\/www.bonitastay.com\/wp-content\/uploads\/2023\/08\/BPAZ-Formato-WEB-691-\u00d7-461-px-691-\u00d7-461-px-1920-\u00d7-865-px-100x50.png\" data-in=\"o:0;\" data-out=\"a:false;\">\n\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" src=\"\/\/www.bonitastay.com\/wp-content\/plugins\/revslider\/public\/assets\/assets\/dummy.png\" alt=\"\" title=\"BPAZ Formato WEB (691\u00a0\u00d7\u00a0461\u00a0px) (691\u00a0\u00d7\u00a0461\u00a0px) (1920\u00a0\u00d7\u00a0865\u00a0px)\" width=\"1920\" height=\"865\" class=\"rev-slidebg tp-rs-img rs-lazyload\" data-lazyload=\"\/\/www.bonitastay.com\/wp-content\/uploads\/2023\/08\/BPAZ-Formato-WEB-691-\u00d7-461-px-691-\u00d7-461-px-1920-\u00d7-865-px.png\" data-parallax=\"5\" data-no-retina>\n<!---->\t\t\t\t\t\t<\/rs-slide>\n\t\t\t\t\t\t<rs-slide style=\"position: absolute;\" data-key=\"rs-2\" data-title=\"Slide\" data-thumb=\"\/\/www.bonitastay.com\/wp-content\/uploads\/2024\/06\/BLIGHT-Formato-WEB-1280-x-900-px-1920-x-865-px-1-100x50.png\" data-in=\"o:0;\" data-out=\"a:false;\">\n\t\t\t\t\t\t\t<img decoding=\"async\" src=\"\/\/www.bonitastay.com\/wp-content\/plugins\/revslider\/public\/assets\/assets\/dummy.png\" alt=\"\" title=\"BLIGHT Formato WEB (1280 x 900 px) (1920 x 865 px) (1)\" width=\"1920\" height=\"865\" class=\"rev-slidebg tp-rs-img rs-lazyload\" data-lazyload=\"\/\/www.bonitastay.com\/wp-content\/uploads\/2024\/06\/BLIGHT-Formato-WEB-1280-x-900-px-1920-x-865-px-1.png\" data-parallax=\"5\" data-no-retina>\n<!---->\t\t\t\t\t\t<\/rs-slide>\n\t\t\t\t\t\t<rs-slide style=\"position: absolute;\" data-key=\"rs-3\" data-title=\"Slide\" data-thumb=\"\/\/www.bonitastay.com\/wp-content\/uploads\/2024\/07\/BLIGHT-Formato-WEB-1280-x-900-px-1920-x-865-px-2-100x50.png\" data-in=\"o:0;\" data-out=\"a:false;\">\n\t\t\t\t\t\t\t<img decoding=\"async\" src=\"\/\/www.bonitastay.com\/wp-content\/plugins\/revslider\/public\/assets\/assets\/dummy.png\" alt=\"\" title=\"BLIGHT Formato WEB (1280 x 900 px) (1920 x 865 px) (2)\" width=\"1920\" height=\"865\" class=\"rev-slidebg tp-rs-img rs-lazyload\" data-lazyload=\"\/\/www.bonitastay.com\/wp-content\/uploads\/2024\/07\/BLIGHT-Formato-WEB-1280-x-900-px-1920-x-865-px-2.png\" data-parallax=\"5\" data-no-retina>\n<!---->\t\t\t\t\t\t<\/rs-slide>\n\t\t\t\t\t<\/rs-slides>\n\t\t\t\t<\/rs-module>\n\t\t\t\t<script>\n\t\t\t\t\tsetREVStartSize({c: 'rev_slider_1_1',rl:[1240,1024,778,480],el:[870,768,960,720],gw:[1920,1024,778,480],gh:[870,768,660,420],type:'standard',justify:'',layout:'fullwidth',mh:\"0\"});if (window.RS_MODULES!==undefined && window.RS_MODULES.modules!==undefined && window.RS_MODULES.modules[\"revslider11\"]!==undefined) {window.RS_MODULES.modules[\"revslider11\"].once = false;window.revapi1 = undefined;if (window.RS_MODULES.checkMinimal!==undefined) window.RS_MODULES.checkMinimal()}\n\t\t\t\t<\/script>\n\t\t\t<\/rs-module-wrap>\n\t\t\t<!-- END REVOLUTION SLIDER -->\n<\/div>\r\n\r\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-1594969 qode_elementor_container_inner elementor-section-full_width qode-custom-section-iwt elementor-hidden-mobile elementor-section-height-default elementor-section-height-default parallax_section_no\" data-id=\"1594969\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;animation&quot;:&quot;none&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-f81fa5e\" data-id=\"f81fa5e\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-3671be1 elementor-section-full_width qode_elementor_container_inner elementor-section-height-default elementor-section-height-default parallax_section_no\" data-id=\"3671be1\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-20427a1\" data-id=\"20427a1\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f048796 elementor-widget elementor-widget-bridge_icon_text\" data-id=\"f048796\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"bridge_icon_text.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class='q_icon_with_title small normal_icon '><div class=\"icon_holder \" style=\" \"><span data-icon-type=\"normal\"   style=\"\" class=\"qode_iwt_icon_holder q_font_awsome_icon fa-2x  \"><i class=\"qode_icon_font_awesome fa  qode_iwt_icon_element\" style=\"\" ><\/i><\/span><\/div><div class=\"icon_text_holder\" style=\"\"><div class=\"icon_text_inner\" style=\"\"><h4 class=\"icon_title\" style=\"\">Best Price<\/h4><p style=''>Book from our website and get the best price guaranteed.<\/p><\/div><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-434086e\" data-id=\"434086e\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-dfa8bdc elementor-widget elementor-widget-bridge_icon_text\" data-id=\"dfa8bdc\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"bridge_icon_text.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class='q_icon_with_title small normal_icon '><div class=\"icon_holder \" style=\" \"><span data-icon-type=\"normal\"   style=\"\" class=\"qode_iwt_icon_holder q_font_awsome_icon fa-2x  \"><i class=\"qode_icon_font_awesome fa  qode_iwt_icon_element\" style=\"\" ><\/i><\/span><\/div><div class=\"icon_text_holder\" style=\"\"><div class=\"icon_text_inner\" style=\"\"><h4 class=\"icon_title\" style=\"\">Long Stay<\/h4><p style=''>15% discount for stays of 14 nights or more.<\/p><\/div><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-03dfd6c\" data-id=\"03dfd6c\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-71b5c52 elementor-widget elementor-widget-bridge_icon_text\" data-id=\"71b5c52\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"bridge_icon_text.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class='q_icon_with_title small normal_icon '><div class=\"icon_holder \" style=\" \"><span data-icon-type=\"normal\"   style=\"\" class=\"qode_iwt_icon_holder q_font_awsome_icon fa-2x  \"><i class=\"qode_icon_font_awesome fa  qode_iwt_icon_element\" style=\"\" ><\/i><\/span><\/div><div class=\"icon_text_holder\" style=\"\"><div class=\"icon_text_inner\" style=\"\"><h4 class=\"icon_title\" style=\"\">Adaptability<\/h4><p style=''>We try to adapt by offering early check-in and late check-out.<\/p><\/div><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-540c02f qode_elementor_container_inner elementor-section-full_width qode-custom-section-iwt elementor-hidden-desktop elementor-hidden-tablet elementor-hidden-mobile elementor-section-height-default elementor-section-height-default parallax_section_no elementor-invisible\" data-id=\"540c02f\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;animation&quot;:&quot;fadeInUp&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-b043bc8\" data-id=\"b043bc8\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-b2dd2aa elementor-section-full_width qode_elementor_container_inner elementor-section-height-default elementor-section-height-default parallax_section_no\" data-id=\"b2dd2aa\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-5e9bb0b\" data-id=\"5e9bb0b\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5d51936 elementor-widget elementor-widget-bridge_icon_text\" data-id=\"5d51936\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"bridge_icon_text.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class='q_icon_with_title small normal_icon '><div class=\"icon_holder \" style=\" \"><span data-icon-type=\"normal\"   style=\"\" class=\"qode_iwt_icon_holder q_font_awsome_icon fa-2x  \"><i class=\"qode_icon_font_awesome fa  qode_iwt_icon_element\" style=\"\" ><\/i><\/span><\/div><div class=\"icon_text_holder\" style=\"\"><div class=\"icon_text_inner\" style=\"\"><h4 class=\"icon_title\" style=\"\">Best Price<\/h4><p style=''>Book from our website and get the best price guaranteed.<\/p><\/div><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-757c42e\" data-id=\"757c42e\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-9817336 elementor-widget elementor-widget-bridge_icon_text\" data-id=\"9817336\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"bridge_icon_text.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class='q_icon_with_title small normal_icon '><div class=\"icon_holder \" style=\" \"><span data-icon-type=\"normal\"   style=\"\" class=\"qode_iwt_icon_holder q_font_awsome_icon fa-2x  \"><i class=\"qode_icon_font_awesome fa  qode_iwt_icon_element\" style=\"\" ><\/i><\/span><\/div><div class=\"icon_text_holder\" style=\"\"><div class=\"icon_text_inner\" style=\"\"><h4 class=\"icon_title\" style=\"\">Long Stay<\/h4><p style=''>15% discount for stays of 14 nights or more.<\/p><\/div><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-970db0f\" data-id=\"970db0f\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1e18bc2 elementor-widget elementor-widget-bridge_icon_text\" data-id=\"1e18bc2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"bridge_icon_text.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class='q_icon_with_title small normal_icon '><div class=\"icon_holder \" style=\" \"><span data-icon-type=\"normal\"   style=\"\" class=\"qode_iwt_icon_holder q_font_awsome_icon fa-2x  \"><i class=\"qode_icon_font_awesome fa  qode_iwt_icon_element\" style=\"\" ><\/i><\/span><\/div><div class=\"icon_text_holder\" style=\"\"><div class=\"icon_text_inner\" style=\"\"><h4 class=\"icon_title\" style=\"\">Adaptability<\/h4><p style=''>We try to adapt by offering early check-in and late check-out.<\/p><\/div><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-9c31a3d elementor-hidden-mobile elementor-section-boxed elementor-section-height-default elementor-section-height-default parallax_section_no qode_elementor_container_no\" data-id=\"9c31a3d\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;animation&quot;:&quot;none&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-aa1b8d9\" data-id=\"aa1b8d9\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-eec07fb elementor-widget elementor-widget-qi_addons_for_elementor_section_title\" data-id=\"eec07fb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"qi_addons_for_elementor_section_title.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"qodef-shortcode qodef-m qodef-qi-section-title qodef-decoration--italic qodef-link--underline-draw qodef-subtitle-icon--left\">\n\t\t\t<h2 class=\"qodef-m-title\">\n\t\tChoose your home for the best vacations\t<\/h2>\n\t\t\t\t<h6 class=\"qodef-m-subtitle\">\n\t\tYou will feel better than at home, they are all prepared and decorated to make your vacations wonderful. Welcome to Bonita Stay! \t\t\t<\/h6>\n\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-edf9942 elementor-hidden-desktop elementor-hidden-tablet elementor-section-boxed elementor-section-height-default elementor-section-height-default parallax_section_no qode_elementor_container_no\" data-id=\"edf9942\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-4e23043\" data-id=\"4e23043\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-10b6616 elementor-widget elementor-widget-qi_addons_for_elementor_section_title\" data-id=\"10b6616\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"qi_addons_for_elementor_section_title.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"qodef-shortcode qodef-m qodef-qi-section-title qodef-decoration--italic qodef-link--underline-draw qodef-subtitle-icon--left\">\n\t\t\t<h2 class=\"qodef-m-title\">\n\t\tChoose your home  \t<\/h2>\n\t\t\t\t<h6 class=\"qodef-m-subtitle\">\n\t\tYou will feel better than at home, they are all prepared and decorated to make your vacations wonderful. Welcome to Bonita Stay! \t\t\t<\/h6>\n\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-1f700aa elementor-section-boxed elementor-section-height-default elementor-section-height-default parallax_section_no qode_elementor_container_no\" data-id=\"1f700aa\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;animation&quot;:&quot;none&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-c687d7f\" data-id=\"c687d7f\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-192fc7e elementor-widget elementor-widget-html\" data-id=\"192fc7e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<script type=\"text\/javascript\" src=\"https:\/\/bookonline.pro\/widgets\/search\/dist\/index.js\" defer><\/script>\n    <div data-accommodations-filter=\"none\" data-target=\"_blank\" class=\"avaibook-search-widget\" data-widget-id=\"86133\" data-widget-token=\"oCa7vaK2FjzqazsXuHg9Og==\" data-background-color=\"#FFFFFF\" data-main-color=\"#279db7\" data-border-radius=\"3px\" data-shadow=\"0 2px 20px rgb(0 0 0 \/ 16%)\" data-padding=\"1rem\" data-language=\"es\"><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-70cb883e elementor-section-boxed elementor-section-height-default elementor-section-height-default parallax_section_no qode_elementor_container_no\" data-id=\"70cb883e\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;animation&quot;:&quot;none&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-739e35d\" data-id=\"739e35d\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-67aabafb elementor-widget elementor-widget-qi_addons_for_elementor_section_title\" data-id=\"67aabafb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"qi_addons_for_elementor_section_title.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"qodef-shortcode qodef-m qodef-qi-section-title qodef-decoration--italic qodef-link--underline-draw qodef-subtitle-icon--left\">\n\t\t\t\t\t\t<h6 class=\"qodef-m-subtitle\">\n\t\tCall us or write to us if you want us to help you find your availability\t\t\t<\/h6>\n\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-36a61668 elementor-section-boxed elementor-section-height-default elementor-section-height-default parallax_section_no qode_elementor_container_no\" data-id=\"36a61668\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;animation&quot;:&quot;none&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-4eeea925\" data-id=\"4eeea925\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-778b2246\" data-id=\"778b2246\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-437d5022 elementor-align-center elementor-widget elementor-widget-button\" data-id=\"437d5022\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-xs\" href=\"tel:+34919613311\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-phone-alt\"><\/i>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\"> +34 919 613 311<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-510a1ee3\" data-id=\"510a1ee3\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-10306ca3 elementor-align-center elementor-widget elementor-widget-button\" data-id=\"10306ca3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-xs\" href=\"mailto:hola@bonitastay.com\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-mail-bulk\"><\/i>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">hola@bonitastay.com<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-540cdf0c\" data-id=\"540cdf0c\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-5db9f7e2 elementor-section-full_width qode_elementor_container_inner elementor-section-height-default elementor-section-height-default parallax_section_no\" data-id=\"5db9f7e2\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;animation&quot;:&quot;none&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-79e74b51\" data-id=\"79e74b51\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-17d60670 elementor-widget elementor-widget-qi_addons_for_elementor_section_title\" data-id=\"17d60670\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"qi_addons_for_elementor_section_title.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"qodef-shortcode qodef-m qodef-qi-section-title qodef-decoration--italic qodef-link--underline-draw qodef-subtitle-icon--left\">\n\t\t\t\t\t\t<h4 class=\"qodef-m-title\">\n\t\tJ\u00e1vea - B SKY\t<\/h4>\n\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-605cf3bb animated-slow elementor-invisible elementor-widget elementor-widget-bridge_image_gallery\" data-id=\"605cf3bb\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeIn&quot;}\" data-widget_type=\"bridge_image_gallery.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"qode-image-gallery\"><div class=\"qode-image-gallery-inner\"><div class=\"qode-image-gallery-slides flexslider_slide flexslider\" data-interval=\"0\" data-flex_fx=\"slide\"data-control=\"false\"data-direction=\"true\"data-drag=\"false\"><ul class=\"slides\"><li><a itemprop=\"url\" href=\"https:\/\/bookonline.pro\/en\/property\/249435?guests=1\" target=\"_self\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.bonitastay.com\/wp-content\/uploads\/2023\/08\/2-1-355x229.png\" alt=\"\" width=\"355\" height=\"229\" \/><\/a><\/li><li><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.bonitastay.com\/wp-content\/uploads\/2023\/08\/1-1-355x229.png\" alt=\"\" width=\"355\" height=\"229\" \/><\/li><li><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.bonitastay.com\/wp-content\/uploads\/2023\/07\/2-2-355x229.png\" alt=\"\" width=\"355\" height=\"229\" \/><\/li><li><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.bonitastay.com\/wp-content\/uploads\/2023\/07\/3-2-355x229.png\" alt=\"\" width=\"355\" height=\"229\" \/><\/li><li><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.bonitastay.com\/wp-content\/uploads\/2023\/07\/4-2-355x229.png\" alt=\"\" width=\"355\" height=\"229\" \/><\/li><li><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.bonitastay.com\/wp-content\/uploads\/2023\/08\/3-1-355x229.png\" alt=\"\" width=\"355\" height=\"229\" \/><\/li><li><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.bonitastay.com\/wp-content\/uploads\/2023\/07\/7-2-355x229.png\" alt=\"\" width=\"355\" height=\"229\" \/><\/li><li><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.bonitastay.com\/wp-content\/uploads\/2023\/07\/8-2-355x229.png\" alt=\"\" width=\"355\" height=\"229\" \/><\/li><li><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.bonitastay.com\/wp-content\/uploads\/2023\/07\/9-2-355x229.png\" alt=\"\" width=\"355\" height=\"229\" \/><\/li><li><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.bonitastay.com\/wp-content\/uploads\/2023\/07\/10-2-355x229.png\" alt=\"\" width=\"355\" height=\"229\" \/><\/li><li><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.bonitastay.com\/wp-content\/uploads\/2023\/07\/11-2-355x229.png\" alt=\"\" width=\"355\" height=\"229\" \/><\/li><li><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.bonitastay.com\/wp-content\/uploads\/2023\/07\/12-2-355x229.png\" alt=\"\" width=\"355\" height=\"229\" \/><\/li><li><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.bonitastay.com\/wp-content\/uploads\/2023\/07\/13-2-355x229.png\" alt=\"\" width=\"355\" height=\"229\" \/><\/li><li><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.bonitastay.com\/wp-content\/uploads\/2023\/07\/14-2-355x229.png\" alt=\"\" width=\"355\" height=\"229\" \/><\/li><li><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.bonitastay.com\/wp-content\/uploads\/2023\/07\/15-2-355x229.png\" alt=\"\" width=\"355\" height=\"229\" \/><\/li><li><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.bonitastay.com\/wp-content\/uploads\/2023\/07\/16-2-355x229.png\" alt=\"\" width=\"355\" height=\"229\" \/><\/li><li><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.bonitastay.com\/wp-content\/uploads\/2023\/07\/17-2-355x229.png\" alt=\"\" width=\"355\" height=\"229\" \/><\/li><li><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.bonitastay.com\/wp-content\/uploads\/2023\/07\/18-2-355x229.png\" alt=\"\" width=\"355\" height=\"229\" \/><\/li><li><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.bonitastay.com\/wp-content\/uploads\/2023\/07\/19-2-355x229.png\" alt=\"\" width=\"355\" height=\"229\" \/><\/li><li><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.bonitastay.com\/wp-content\/uploads\/2023\/07\/20-2-355x229.png\" alt=\"\" width=\"355\" height=\"229\" \/><\/li><li><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.bonitastay.com\/wp-content\/uploads\/2023\/07\/21-2-355x229.png\" alt=\"\" width=\"355\" height=\"229\" \/><\/li><li><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.bonitastay.com\/wp-content\/uploads\/2023\/07\/22-2-355x229.png\" alt=\"\" width=\"355\" height=\"229\" \/><\/li><li><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.bonitastay.com\/wp-content\/uploads\/2023\/07\/23-2-355x229.png\" alt=\"\" width=\"355\" height=\"229\" \/><\/li><li><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.bonitastay.com\/wp-content\/uploads\/2023\/07\/24-2-355x229.png\" alt=\"\" width=\"355\" height=\"229\" \/><\/li><li><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.bonitastay.com\/wp-content\/uploads\/2023\/07\/25-2-355x229.png\" alt=\"\" width=\"355\" height=\"229\" \/><\/li><li><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.bonitastay.com\/wp-content\/uploads\/2023\/07\/26-2-355x229.png\" alt=\"\" width=\"355\" height=\"229\" \/><\/li><li><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.bonitastay.com\/wp-content\/uploads\/2023\/07\/27-1-355x229.png\" alt=\"\" width=\"355\" height=\"229\" \/><\/li><li><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.bonitastay.com\/wp-content\/uploads\/2023\/07\/28-2-355x229.png\" alt=\"\" width=\"355\" height=\"229\" \/><\/li><li><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.bonitastay.com\/wp-content\/uploads\/2023\/07\/29-2-355x229.png\" alt=\"\" width=\"355\" height=\"229\" \/><\/li><li><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.bonitastay.com\/wp-content\/uploads\/2023\/07\/30-2-355x229.png\" alt=\"\" width=\"355\" height=\"229\" \/><\/li><li><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.bonitastay.com\/wp-content\/uploads\/2023\/07\/31-2-355x229.png\" alt=\"\" width=\"355\" height=\"229\" \/><\/li><li><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.bonitastay.com\/wp-content\/uploads\/2023\/07\/32-2-355x229.png\" alt=\"\" width=\"355\" height=\"229\" \/><\/li><li><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.bonitastay.com\/wp-content\/uploads\/2023\/07\/33-2-355x229.png\" alt=\"\" width=\"355\" height=\"229\" \/><\/li><li><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.bonitastay.com\/wp-content\/uploads\/2023\/07\/34-2-355x229.png\" alt=\"\" width=\"355\" height=\"229\" \/><\/li><li><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.bonitastay.com\/wp-content\/uploads\/2023\/07\/35-2-355x229.png\" alt=\"\" width=\"355\" height=\"229\" \/><\/li><li><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.bonitastay.com\/wp-content\/uploads\/2023\/07\/36-2-355x229.png\" alt=\"\" width=\"355\" height=\"229\" \/><\/li><li><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.bonitastay.com\/wp-content\/uploads\/2023\/07\/37-2-355x229.png\" alt=\"\" width=\"355\" height=\"229\" \/><\/li><li><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.bonitastay.com\/wp-content\/uploads\/2023\/07\/38-2-355x229.png\" alt=\"\" width=\"355\" height=\"229\" \/><\/li><li><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.bonitastay.com\/wp-content\/uploads\/2023\/07\/39-2-355x229.png\" alt=\"\" width=\"355\" height=\"229\" \/><\/li><li><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.bonitastay.com\/wp-content\/uploads\/2023\/07\/40-2-355x229.png\" alt=\"\" width=\"355\" height=\"229\" \/><\/li><li><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.bonitastay.com\/wp-content\/uploads\/2023\/08\/6-355x229.png\" alt=\"\" width=\"355\" height=\"229\" \/><\/li><li><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.bonitastay.com\/wp-content\/uploads\/2023\/08\/8-1-355x229.png\" alt=\"\" width=\"355\" height=\"229\" \/><\/li><li><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.bonitastay.com\/wp-content\/uploads\/2023\/08\/7-355x229.png\" alt=\"\" width=\"355\" height=\"229\" \/><\/li><li><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.bonitastay.com\/wp-content\/uploads\/2023\/07\/41-2-355x229.png\" alt=\"\" width=\"355\" height=\"229\" \/><\/li><li><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.bonitastay.com\/wp-content\/uploads\/2023\/07\/42-2-355x229.png\" alt=\"\" width=\"355\" height=\"229\" \/><\/li><li><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.bonitastay.com\/wp-content\/uploads\/2023\/07\/43-2-355x229.png\" alt=\"\" width=\"355\" height=\"229\" \/><\/li><li><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.bonitastay.com\/wp-content\/uploads\/2023\/08\/4-355x229.png\" alt=\"\" width=\"355\" height=\"229\" \/><\/li><li><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.bonitastay.com\/wp-content\/uploads\/2023\/07\/44-2-355x229.png\" alt=\"\" width=\"355\" height=\"229\" \/><\/li><li><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.bonitastay.com\/wp-content\/uploads\/2023\/07\/45-2-355x229.png\" alt=\"\" width=\"355\" height=\"229\" \/><\/li><li><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.bonitastay.com\/wp-content\/uploads\/2023\/07\/46-2-355x229.png\" alt=\"\" width=\"355\" height=\"229\" \/><\/li><li><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.bonitastay.com\/wp-content\/uploads\/2023\/07\/47-2-355x229.png\" alt=\"\" width=\"355\" height=\"229\" \/><\/li><li><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.bonitastay.com\/wp-content\/uploads\/2023\/07\/48-2-355x229.png\" alt=\"\" width=\"355\" height=\"229\" \/><\/li><li><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.bonitastay.com\/wp-content\/uploads\/2023\/07\/49-2-355x229.png\" alt=\"\" width=\"355\" height=\"229\" \/><\/li><li><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.bonitastay.com\/wp-content\/uploads\/2023\/07\/50-355x229.png\" alt=\"\" width=\"355\" height=\"229\" \/><\/li><li><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.bonitastay.com\/wp-content\/uploads\/2023\/08\/5-1-355x229.png\" alt=\"\" width=\"355\" height=\"229\" \/><\/li><\/div><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-668ab828 elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"668ab828\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-house-user\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Capacity 6 people<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-bed\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">4 Bedrooms - 3 Bathrooms<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-swimming-pool\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Heated Swimming Pool<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6f47943c elementor-widget elementor-widget-button\" data-id=\"6f47943c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-xs\" href=\"https:\/\/bookonline.pro\/en\/property\/249435?guests=1\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">BOOK<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-355175a5\" data-id=\"355175a5\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-181b713e elementor-widget elementor-widget-qi_addons_for_elementor_section_title\" data-id=\"181b713e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"qi_addons_for_elementor_section_title.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"qodef-shortcode qodef-m qodef-qi-section-title qodef-decoration--italic qodef-link--underline-draw qodef-subtitle-icon--left\">\n\t\t\t\t\t\t<h4 class=\"qodef-m-title\">\n\t\tJ\u00e1vea - B LIGHT\t<\/h4>\n\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3f015416 animated-slow elementor-invisible elementor-widget elementor-widget-bridge_image_gallery\" data-id=\"3f015416\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeIn&quot;}\" data-widget_type=\"bridge_image_gallery.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"qode-image-gallery\"><div class=\"qode-image-gallery-inner\"><div class=\"qode-image-gallery-slides flexslider_slide flexslider\" data-interval=\"0\" data-flex_fx=\"slide\"data-control=\"false\"data-direction=\"true\"data-drag=\"false\"><ul class=\"slides\"><li><a itemprop=\"url\" href=\"https:\/\/bookonline.pro\/en\/property\/249209?guests=1\" target=\"_self\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.bonitastay.com\/wp-content\/uploads\/2024\/06\/Roble_09_019-scaled-355x229.jpg\" alt=\"\" width=\"355\" height=\"229\" \/><\/a><\/li><li><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.bonitastay.com\/wp-content\/uploads\/2024\/06\/Roble_09_018-scaled-355x229.jpg\" alt=\"\" width=\"355\" height=\"229\" \/><\/li><li><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.bonitastay.com\/wp-content\/uploads\/2024\/06\/DJI_0235-scaled-355x229.jpg\" alt=\"\" width=\"355\" height=\"229\" \/><\/li><li><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.bonitastay.com\/wp-content\/uploads\/2024\/06\/DJI_0237-scaled-355x229.jpg\" alt=\"\" width=\"355\" height=\"229\" \/><\/li><li><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.bonitastay.com\/wp-content\/uploads\/2024\/06\/DJI_0239-scaled-355x229.jpg\" alt=\"\" width=\"355\" height=\"229\" \/><\/li><li><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.bonitastay.com\/wp-content\/uploads\/2024\/06\/Roble_09_017-scaled-355x229.jpg\" alt=\"\" width=\"355\" height=\"229\" \/><\/li><li><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.bonitastay.com\/wp-content\/uploads\/2024\/06\/Roble_09_016-scaled-355x229.jpg\" alt=\"\" width=\"355\" height=\"229\" \/><\/li><li><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.bonitastay.com\/wp-content\/uploads\/2024\/06\/Roble_09_015-scaled-355x229.jpg\" alt=\"\" width=\"355\" height=\"229\" \/><\/li><li><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.bonitastay.com\/wp-content\/uploads\/2024\/06\/DJI_0238-scaled-355x229.jpg\" alt=\"\" width=\"355\" height=\"229\" \/><\/li><li><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.bonitastay.com\/wp-content\/uploads\/2024\/06\/Roble_09_020-scaled-355x229.jpg\" alt=\"\" width=\"355\" height=\"229\" \/><\/li><li><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.bonitastay.com\/wp-content\/uploads\/2024\/06\/Roble_09_021-scaled-355x229.jpg\" alt=\"\" width=\"355\" height=\"229\" \/><\/li><li><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.bonitastay.com\/wp-content\/uploads\/2024\/06\/Roble_09_025-scaled-355x229.jpg\" alt=\"\" width=\"355\" height=\"229\" \/><\/li><li><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.bonitastay.com\/wp-content\/uploads\/2023\/07\/8-1-355x229.png\" alt=\"\" width=\"355\" height=\"229\" \/><\/li><li><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.bonitastay.com\/wp-content\/uploads\/2023\/07\/9-1-355x229.png\" alt=\"\" width=\"355\" height=\"229\" \/><\/li><li><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.bonitastay.com\/wp-content\/uploads\/2023\/07\/10-1-355x229.png\" alt=\"\" width=\"355\" height=\"229\" \/><\/li><li><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.bonitastay.com\/wp-content\/uploads\/2023\/07\/11-1-355x229.png\" alt=\"\" width=\"355\" height=\"229\" \/><\/li><li><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.bonitastay.com\/wp-content\/uploads\/2023\/07\/12-1-355x229.png\" alt=\"\" width=\"355\" height=\"229\" \/><\/li><li><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.bonitastay.com\/wp-content\/uploads\/2023\/07\/13-1-355x229.png\" alt=\"\" width=\"355\" height=\"229\" \/><\/li><li><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.bonitastay.com\/wp-content\/uploads\/2023\/07\/14-1-355x229.png\" alt=\"\" width=\"355\" height=\"229\" \/><\/li><li><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.bonitastay.com\/wp-content\/uploads\/2023\/07\/15-1-355x229.png\" alt=\"\" width=\"355\" height=\"229\" \/><\/li><li><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.bonitastay.com\/wp-content\/uploads\/2023\/07\/16-1-355x229.png\" alt=\"\" width=\"355\" height=\"229\" \/><\/li><li><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.bonitastay.com\/wp-content\/uploads\/2023\/07\/17-1-355x229.png\" alt=\"\" width=\"355\" height=\"229\" \/><\/li><li><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.bonitastay.com\/wp-content\/uploads\/2023\/07\/18-1-355x229.png\" alt=\"\" width=\"355\" height=\"229\" \/><\/li><li><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.bonitastay.com\/wp-content\/uploads\/2023\/07\/19-1-355x229.png\" alt=\"\" width=\"355\" height=\"229\" \/><\/li><li><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.bonitastay.com\/wp-content\/uploads\/2023\/07\/20-1-355x229.png\" alt=\"\" width=\"355\" height=\"229\" \/><\/li><li><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.bonitastay.com\/wp-content\/uploads\/2024\/06\/Roble_09_014-scaled-355x229.jpg\" alt=\"\" width=\"355\" height=\"229\" \/><\/li><li><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.bonitastay.com\/wp-content\/uploads\/2024\/06\/Roble_09_013-scaled-355x229.jpg\" alt=\"\" width=\"355\" height=\"229\" \/><\/li><li><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.bonitastay.com\/wp-content\/uploads\/2024\/06\/Roble_09_027-scaled-355x229.jpg\" alt=\"\" width=\"355\" height=\"229\" \/><\/li><li><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.bonitastay.com\/wp-content\/uploads\/2024\/06\/Roble_09_012-scaled-355x229.jpg\" alt=\"\" width=\"355\" height=\"229\" \/><\/li><li><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.bonitastay.com\/wp-content\/uploads\/2024\/06\/Roble_09_010-scaled-355x229.jpg\" alt=\"\" width=\"355\" height=\"229\" \/><\/li><li><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.bonitastay.com\/wp-content\/uploads\/2024\/06\/Roble_09_011-scaled-355x229.jpg\" alt=\"\" width=\"355\" height=\"229\" \/><\/li><li><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.bonitastay.com\/wp-content\/uploads\/2024\/06\/Roble_09_009-scaled-355x229.jpg\" alt=\"\" width=\"355\" height=\"229\" \/><\/li><li><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.bonitastay.com\/wp-content\/uploads\/2023\/07\/28-1-355x229.png\" alt=\"\" width=\"355\" height=\"229\" \/><\/li><li><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.bonitastay.com\/wp-content\/uploads\/2023\/07\/29-1-355x229.png\" alt=\"\" width=\"355\" height=\"229\" \/><\/li><li><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.bonitastay.com\/wp-content\/uploads\/2024\/06\/Roble_09_002-scaled-355x229.jpg\" alt=\"\" width=\"355\" height=\"229\" \/><\/li><li><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.bonitastay.com\/wp-content\/uploads\/2024\/06\/Roble_09_004-scaled-355x229.jpg\" alt=\"\" width=\"355\" height=\"229\" \/><\/li><li><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.bonitastay.com\/wp-content\/uploads\/2024\/06\/Roble_09_003-scaled-355x229.jpg\" alt=\"\" width=\"355\" height=\"229\" \/><\/li><li><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.bonitastay.com\/wp-content\/uploads\/2024\/06\/Roble_09_001-scaled-355x229.jpg\" alt=\"\" width=\"355\" height=\"229\" \/><\/li><li><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.bonitastay.com\/wp-content\/uploads\/2024\/06\/Roble_09_006-scaled-355x229.jpg\" alt=\"\" width=\"355\" height=\"229\" \/><\/li><li><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.bonitastay.com\/wp-content\/uploads\/2024\/06\/D46A9963-scaled-355x229.jpg\" alt=\"\" width=\"355\" height=\"229\" \/><\/li><li><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.bonitastay.com\/wp-content\/uploads\/2023\/07\/35-1-355x229.png\" alt=\"\" width=\"355\" height=\"229\" \/><\/li><li><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.bonitastay.com\/wp-content\/uploads\/2023\/07\/36-1-355x229.png\" alt=\"\" width=\"355\" height=\"229\" \/><\/li><li><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.bonitastay.com\/wp-content\/uploads\/2023\/07\/37-1-355x229.png\" alt=\"\" width=\"355\" height=\"229\" \/><\/li><li><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.bonitastay.com\/wp-content\/uploads\/2023\/07\/38-1-355x229.png\" alt=\"\" width=\"355\" height=\"229\" \/><\/li><li><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.bonitastay.com\/wp-content\/uploads\/2023\/07\/39-1-355x229.png\" alt=\"\" width=\"355\" height=\"229\" \/><\/li><li><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.bonitastay.com\/wp-content\/uploads\/2024\/06\/Roble_09_024-scaled-355x229.jpg\" alt=\"\" width=\"355\" height=\"229\" \/><\/li><li><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.bonitastay.com\/wp-content\/uploads\/2023\/07\/40-1-355x229.png\" alt=\"\" width=\"355\" height=\"229\" \/><\/li><li><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.bonitastay.com\/wp-content\/uploads\/2024\/06\/Roble_09_005-scaled-355x229.jpg\" alt=\"\" width=\"355\" height=\"229\" \/><\/li><li><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.bonitastay.com\/wp-content\/uploads\/2023\/07\/42-1-355x229.png\" alt=\"\" width=\"355\" height=\"229\" \/><\/li><li><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.bonitastay.com\/wp-content\/uploads\/2023\/07\/43-1-355x229.png\" alt=\"\" width=\"355\" height=\"229\" \/><\/li><li><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.bonitastay.com\/wp-content\/uploads\/2023\/07\/44-1-355x229.png\" alt=\"\" width=\"355\" height=\"229\" \/><\/li><li><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.bonitastay.com\/wp-content\/uploads\/2023\/07\/47-1-355x229.png\" alt=\"\" width=\"355\" height=\"229\" \/><\/li><li><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.bonitastay.com\/wp-content\/uploads\/2024\/06\/Roble_09_008-scaled-355x229.jpg\" alt=\"\" width=\"355\" height=\"229\" \/><\/li><li><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.bonitastay.com\/wp-content\/uploads\/2024\/06\/Roble_09_007-scaled-355x229.jpg\" alt=\"\" width=\"355\" height=\"229\" \/><\/li><li><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.bonitastay.com\/wp-content\/uploads\/2024\/06\/sillas-scaled-355x229.jpg\" alt=\"\" width=\"355\" height=\"229\" \/><\/li><li><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.bonitastay.com\/wp-content\/uploads\/2024\/06\/sillas-2-scaled-355x229.jpg\" alt=\"\" width=\"355\" height=\"229\" \/><\/li><li><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.bonitastay.com\/wp-content\/uploads\/2024\/06\/Roble_09_026-scaled-355x229.jpg\" alt=\"\" width=\"355\" height=\"229\" \/><\/li><li><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.bonitastay.com\/wp-content\/uploads\/2024\/06\/Roble_09_023-scaled-355x229.jpg\" alt=\"\" width=\"355\" height=\"229\" \/><\/li><li><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.bonitastay.com\/wp-content\/uploads\/2024\/06\/Roble_09_022-scaled-355x229.jpg\" alt=\"\" width=\"355\" height=\"229\" \/><\/li><\/div><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-643ac22 elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"643ac22\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-house-user\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Capacity 9 people<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-bed\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">4 Bedrooms - 5 Bathrooms<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-swimming-pool\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Heated Swimming Pool\u200b<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-213d257 elementor-widget elementor-widget-button\" data-id=\"213d257\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-xs\" href=\"https:\/\/bookonline.pro\/en\/property\/249209?guests=1\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">BOOK<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-2d84db5\" data-id=\"2d84db5\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-fd46441 elementor-widget elementor-widget-qi_addons_for_elementor_section_title\" data-id=\"fd46441\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"qi_addons_for_elementor_section_title.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"qodef-shortcode qodef-m qodef-qi-section-title qodef-decoration--italic qodef-link--underline-draw qodef-subtitle-icon--left\">\n\t\t\t\t\t\t<h4 class=\"qodef-m-title\">\n\t\tJ\u00e1vea - B CAPE\t<\/h4>\n\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ff4f085 animated-slow elementor-invisible elementor-widget elementor-widget-bridge_image_gallery\" data-id=\"ff4f085\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeIn&quot;}\" data-widget_type=\"bridge_image_gallery.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"qode-image-gallery\"><div class=\"qode-image-gallery-inner\"><div class=\"qode-image-gallery-slides flexslider_slide flexslider\" data-interval=\"0\" data-flex_fx=\"slide\"data-control=\"false\"data-direction=\"true\"data-drag=\"false\"><ul class=\"slides\"><li><a itemprop=\"url\" href=\"https:\/\/bookonline.pro\/en\/property\/249209?guests=1\" target=\"_self\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.bonitastay.com\/wp-content\/uploads\/2024\/07\/La-Plana_01_002-1-scaled-355x229.jpg\" alt=\"\" width=\"355\" height=\"229\" \/><\/a><\/li><li><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.bonitastay.com\/wp-content\/uploads\/2024\/07\/La-Plana_01_003-1-scaled-355x229.jpg\" alt=\"\" width=\"355\" height=\"229\" \/><\/li><li><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.bonitastay.com\/wp-content\/uploads\/2024\/07\/La-Plana_01_001-scaled-355x229.jpg\" alt=\"\" width=\"355\" height=\"229\" \/><\/li><li><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.bonitastay.com\/wp-content\/uploads\/2024\/07\/La-Plana_01_004-scaled-355x229.jpg\" alt=\"\" width=\"355\" height=\"229\" \/><\/li><li><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.bonitastay.com\/wp-content\/uploads\/2024\/07\/La-Plana_11_052-scaled-355x229.jpg\" alt=\"\" width=\"355\" height=\"229\" \/><\/li><li><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.bonitastay.com\/wp-content\/uploads\/2024\/07\/La-Plana_11_050-scaled-355x229.jpg\" alt=\"\" width=\"355\" height=\"229\" \/><\/li><li><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.bonitastay.com\/wp-content\/uploads\/2024\/07\/La-Plana_11_051-scaled-355x229.jpg\" alt=\"\" width=\"355\" height=\"229\" \/><\/li><li><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.bonitastay.com\/wp-content\/uploads\/2024\/07\/La-Plana_11_017-scaled-355x229.jpg\" alt=\"\" width=\"355\" height=\"229\" \/><\/li><li><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.bonitastay.com\/wp-content\/uploads\/2024\/07\/La-Plana_11_018-scaled-355x229.jpg\" alt=\"\" width=\"355\" height=\"229\" \/><\/li><li><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.bonitastay.com\/wp-content\/uploads\/2024\/07\/La-Plana_01_006-scaled-355x229.jpg\" alt=\"\" width=\"355\" height=\"229\" \/><\/li><li><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.bonitastay.com\/wp-content\/uploads\/2024\/07\/La-Plana_01_005-1-scaled-355x229.jpg\" alt=\"\" width=\"355\" height=\"229\" \/><\/li><li><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.bonitastay.com\/wp-content\/uploads\/2024\/07\/La-Plana_01_005-scaled-355x229.jpg\" alt=\"\" width=\"355\" height=\"229\" \/><\/li><li><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.bonitastay.com\/wp-content\/uploads\/2024\/07\/La-Plana_01_013-scaled-355x229.jpg\" alt=\"\" width=\"355\" height=\"229\" \/><\/li><li><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.bonitastay.com\/wp-content\/uploads\/2024\/07\/La-Plana_01_012-scaled-355x229.jpg\" alt=\"\" width=\"355\" height=\"229\" \/><\/li><li><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.bonitastay.com\/wp-content\/uploads\/2024\/07\/La-Plana_01_011-scaled-355x229.jpg\" alt=\"\" width=\"355\" height=\"229\" \/><\/li><li><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.bonitastay.com\/wp-content\/uploads\/2024\/07\/La-Plana_01_010-scaled-355x229.jpg\" alt=\"\" width=\"355\" height=\"229\" \/><\/li><li><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.bonitastay.com\/wp-content\/uploads\/2024\/07\/La-Plana_01_009-scaled-355x229.jpg\" alt=\"\" width=\"355\" height=\"229\" \/><\/li><li><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.bonitastay.com\/wp-content\/uploads\/2024\/07\/La-Plana_01_008-scaled-355x229.jpg\" alt=\"\" width=\"355\" height=\"229\" \/><\/li><li><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.bonitastay.com\/wp-content\/uploads\/2024\/07\/La-Plana_01_007-scaled-355x229.jpg\" alt=\"\" width=\"355\" height=\"229\" \/><\/li><li><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.bonitastay.com\/wp-content\/uploads\/2024\/07\/La-Plana_11_057-scaled-355x229.jpg\" alt=\"\" width=\"355\" height=\"229\" \/><\/li><li><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.bonitastay.com\/wp-content\/uploads\/2024\/07\/La-Plana_11_056-scaled-355x229.jpg\" alt=\"\" width=\"355\" height=\"229\" \/><\/li><li><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.bonitastay.com\/wp-content\/uploads\/2024\/07\/La-Plana_11_055-scaled-355x229.jpg\" alt=\"\" width=\"355\" height=\"229\" \/><\/li><li><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.bonitastay.com\/wp-content\/uploads\/2024\/07\/La-Plana_11_054-scaled-355x229.jpg\" alt=\"\" width=\"355\" height=\"229\" \/><\/li><li><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.bonitastay.com\/wp-content\/uploads\/2024\/07\/La-Plana_11_053-scaled-355x229.jpg\" alt=\"\" width=\"355\" height=\"229\" \/><\/li><li><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.bonitastay.com\/wp-content\/uploads\/2024\/07\/La-Plana_11_048-scaled-355x229.jpg\" alt=\"\" width=\"355\" height=\"229\" \/><\/li><li><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.bonitastay.com\/wp-content\/uploads\/2024\/07\/La-Plana_11_047-scaled-355x229.jpg\" alt=\"\" width=\"355\" height=\"229\" \/><\/li><li><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.bonitastay.com\/wp-content\/uploads\/2024\/07\/La-Plana_11_046-scaled-355x229.jpg\" alt=\"\" width=\"355\" height=\"229\" \/><\/li><li><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.bonitastay.com\/wp-content\/uploads\/2024\/07\/La-Plana_11_045-scaled-355x229.jpg\" alt=\"\" width=\"355\" height=\"229\" \/><\/li><li><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.bonitastay.com\/wp-content\/uploads\/2024\/07\/La-Plana_11_044-scaled-355x229.jpg\" alt=\"\" width=\"355\" height=\"229\" \/><\/li><li><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.bonitastay.com\/wp-content\/uploads\/2024\/07\/La-Plana_11_043-scaled-355x229.jpg\" alt=\"\" width=\"355\" height=\"229\" \/><\/li><li><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.bonitastay.com\/wp-content\/uploads\/2024\/07\/La-Plana_11_042-scaled-355x229.jpg\" alt=\"\" width=\"355\" height=\"229\" \/><\/li><li><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.bonitastay.com\/wp-content\/uploads\/2024\/07\/La-Plana_11_041-scaled-355x229.jpg\" alt=\"\" width=\"355\" height=\"229\" \/><\/li><li><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.bonitastay.com\/wp-content\/uploads\/2024\/07\/La-Plana_11_040-scaled-355x229.jpg\" alt=\"\" width=\"355\" height=\"229\" \/><\/li><li><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.bonitastay.com\/wp-content\/uploads\/2024\/07\/La-Plana_11_038-scaled-355x229.jpg\" alt=\"\" width=\"355\" height=\"229\" \/><\/li><li><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.bonitastay.com\/wp-content\/uploads\/2024\/07\/La-Plana_11_037-scaled-355x229.jpg\" alt=\"\" width=\"355\" height=\"229\" \/><\/li><li><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.bonitastay.com\/wp-content\/uploads\/2024\/07\/La-Plana_11_036-scaled-355x229.jpg\" alt=\"\" width=\"355\" height=\"229\" \/><\/li><li><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.bonitastay.com\/wp-content\/uploads\/2024\/07\/La-Plana_11_035-scaled-355x229.jpg\" alt=\"\" width=\"355\" height=\"229\" \/><\/li><li><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.bonitastay.com\/wp-content\/uploads\/2024\/07\/La-Plana_11_034-scaled-355x229.jpg\" alt=\"\" width=\"355\" height=\"229\" \/><\/li><li><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.bonitastay.com\/wp-content\/uploads\/2024\/07\/La-Plana_11_033-scaled-355x229.jpg\" alt=\"\" width=\"355\" height=\"229\" \/><\/li><li><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.bonitastay.com\/wp-content\/uploads\/2024\/07\/La-Plana_11_032-scaled-355x229.jpg\" alt=\"\" width=\"355\" height=\"229\" \/><\/li><li><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.bonitastay.com\/wp-content\/uploads\/2024\/07\/La-Plana_11_031-scaled-355x229.jpg\" alt=\"\" width=\"355\" height=\"229\" \/><\/li><li><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.bonitastay.com\/wp-content\/uploads\/2024\/07\/La-Plana_11_030-scaled-355x229.jpg\" alt=\"\" width=\"355\" height=\"229\" \/><\/li><li><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.bonitastay.com\/wp-content\/uploads\/2024\/07\/La-Plana_11_029-scaled-355x229.jpg\" alt=\"\" width=\"355\" height=\"229\" \/><\/li><li><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.bonitastay.com\/wp-content\/uploads\/2024\/07\/La-Plana_11_028-scaled-355x229.jpg\" alt=\"\" width=\"355\" height=\"229\" \/><\/li><li><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.bonitastay.com\/wp-content\/uploads\/2024\/07\/La-Plana_11_027-scaled-355x229.jpg\" alt=\"\" width=\"355\" height=\"229\" \/><\/li><li><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.bonitastay.com\/wp-content\/uploads\/2024\/07\/La-Plana_11_026-scaled-355x229.jpg\" alt=\"\" width=\"355\" height=\"229\" \/><\/li><li><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.bonitastay.com\/wp-content\/uploads\/2024\/07\/La-Plana_11_025-scaled-355x229.jpg\" alt=\"\" width=\"355\" height=\"229\" \/><\/li><li><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.bonitastay.com\/wp-content\/uploads\/2024\/07\/La-Plana_11_024-scaled-355x229.jpg\" alt=\"\" width=\"355\" height=\"229\" \/><\/li><li><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.bonitastay.com\/wp-content\/uploads\/2024\/07\/La-Plana_11_023-scaled-355x229.jpg\" alt=\"\" width=\"355\" height=\"229\" \/><\/li><li><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.bonitastay.com\/wp-content\/uploads\/2024\/07\/La-Plana_11_022-scaled-355x229.jpg\" alt=\"\" width=\"355\" height=\"229\" \/><\/li><li><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.bonitastay.com\/wp-content\/uploads\/2024\/07\/La-Plana_11_021-scaled-355x229.jpg\" alt=\"\" width=\"355\" height=\"229\" \/><\/li><li><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.bonitastay.com\/wp-content\/uploads\/2024\/07\/La-Plana_11_020-scaled-355x229.jpg\" alt=\"\" width=\"355\" height=\"229\" \/><\/li><li><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.bonitastay.com\/wp-content\/uploads\/2024\/07\/La-Plana_11_019-scaled-355x229.jpg\" alt=\"\" width=\"355\" height=\"229\" \/><\/li><li><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.bonitastay.com\/wp-content\/uploads\/2024\/07\/La-Plana_11_016-scaled-355x229.jpg\" alt=\"\" width=\"355\" height=\"229\" \/><\/li><li><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.bonitastay.com\/wp-content\/uploads\/2024\/07\/La-Plana_11_015-scaled-355x229.jpg\" alt=\"\" width=\"355\" height=\"229\" \/><\/li><li><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.bonitastay.com\/wp-content\/uploads\/2024\/07\/La-Plana_11_012-scaled-355x229.jpg\" alt=\"\" width=\"355\" height=\"229\" \/><\/li><li><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.bonitastay.com\/wp-content\/uploads\/2024\/07\/La-Plana_11_011-scaled-355x229.jpg\" alt=\"\" width=\"355\" height=\"229\" \/><\/li><li><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.bonitastay.com\/wp-content\/uploads\/2024\/07\/La-Plana_11_010-scaled-355x229.jpg\" alt=\"\" width=\"355\" height=\"229\" \/><\/li><li><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.bonitastay.com\/wp-content\/uploads\/2024\/07\/La-Plana_11_009-scaled-355x229.jpg\" alt=\"\" width=\"355\" height=\"229\" \/><\/li><li><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.bonitastay.com\/wp-content\/uploads\/2024\/07\/La-Plana_11_007-scaled-355x229.jpg\" alt=\"\" width=\"355\" height=\"229\" \/><\/li><li><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.bonitastay.com\/wp-content\/uploads\/2024\/07\/La-Plana_11_006-scaled-355x229.jpg\" alt=\"\" width=\"355\" height=\"229\" \/><\/li><li><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.bonitastay.com\/wp-content\/uploads\/2024\/07\/La-Plana_11_005-scaled-355x229.jpg\" alt=\"\" width=\"355\" height=\"229\" \/><\/li><li><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.bonitastay.com\/wp-content\/uploads\/2024\/07\/La-Plana_11_004-scaled-355x229.jpg\" alt=\"\" width=\"355\" height=\"229\" \/><\/li><li><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.bonitastay.com\/wp-content\/uploads\/2024\/07\/La-Plana_11_003-scaled-355x229.jpg\" alt=\"\" width=\"355\" height=\"229\" \/><\/li><li><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.bonitastay.com\/wp-content\/uploads\/2024\/07\/La-Plana_11_002-scaled-355x229.jpg\" alt=\"\" width=\"355\" height=\"229\" \/><\/li><li><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.bonitastay.com\/wp-content\/uploads\/2024\/07\/La-Plana_11_001-scaled-355x229.jpg\" alt=\"\" width=\"355\" height=\"229\" \/><\/li><li><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.bonitastay.com\/wp-content\/uploads\/2024\/07\/DSC_2949-scaled-355x229.jpg\" alt=\"\" width=\"355\" height=\"229\" \/><\/li><\/div><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4327a08 elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"4327a08\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-house-user\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Capacity 8 people<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-bed\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">4 Bedrooms - 4 Bathrooms<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-swimming-pool\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Heated Swimming Pool\u200b<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ada1ae2 elementor-widget elementor-widget-button\" data-id=\"ada1ae2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-xs\" href=\"https:\/\/bookonline.pro\/en\/property\/250746?guests=1\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">BOOK<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-787a963 elementor-section-full_width qode_elementor_container_inner elementor-section-height-default elementor-section-height-default parallax_section_no\" data-id=\"787a963\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;animation&quot;:&quot;none&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-77f61911\" data-id=\"77f61911\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-46dee920 elementor-widget elementor-widget-qi_addons_for_elementor_section_title\" data-id=\"46dee920\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"qi_addons_for_elementor_section_title.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"qodef-shortcode qodef-m qodef-qi-section-title qodef-decoration--italic qodef-link--underline-draw qodef-subtitle-icon--left\">\n\t\t\t\t\t\t<h4 class=\"qodef-m-title\">\n\t\tJ\u00e1vea - B SUN\t<\/h4>\n\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ef38c2b animated-slow elementor-invisible elementor-widget elementor-widget-bridge_image_gallery\" data-id=\"ef38c2b\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeIn&quot;}\" data-widget_type=\"bridge_image_gallery.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"qode-image-gallery\"><div class=\"qode-image-gallery-inner\"><div class=\"qode-image-gallery-slides flexslider_slide flexslider\" data-interval=\"0\" data-flex_fx=\"slide\"data-control=\"false\"data-direction=\"true\"data-drag=\"false\"><ul class=\"slides\"><li><a itemprop=\"url\" href=\"https:\/\/bookonline.pro\/en\/property\/250039?guests=1\" target=\"_self\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.bonitastay.com\/wp-content\/uploads\/2024\/08\/382956_1e82d7da20_6-scaled-355x229.jpg\" alt=\"\" width=\"355\" height=\"229\" \/><\/a><\/li><li><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.bonitastay.com\/wp-content\/uploads\/2024\/08\/382956_5bc928911f_13-scaled-355x229.jpg\" alt=\"\" width=\"355\" height=\"229\" \/><\/li><li><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.bonitastay.com\/wp-content\/uploads\/2024\/08\/382956_6c1e8eaf9f_2-scaled-355x229.jpg\" alt=\"\" width=\"355\" height=\"229\" \/><\/li><li><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.bonitastay.com\/wp-content\/uploads\/2024\/08\/382956_6f2598585d_7-1-scaled-355x229.jpg\" alt=\"\" width=\"355\" height=\"229\" \/><\/li><li><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.bonitastay.com\/wp-content\/uploads\/2024\/08\/382956_81baeac30b_12-scaled-355x229.jpg\" alt=\"\" width=\"355\" height=\"229\" \/><\/li><li><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.bonitastay.com\/wp-content\/uploads\/2024\/08\/382956_98c2a87537_5-1-scaled-355x229.jpg\" alt=\"\" width=\"355\" height=\"229\" \/><\/li><li><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.bonitastay.com\/wp-content\/uploads\/2024\/08\/382956_52d9e973e5_3-1-scaled-355x229.jpg\" alt=\"\" width=\"355\" height=\"229\" \/><\/li><li><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.bonitastay.com\/wp-content\/uploads\/2024\/08\/382956_a3093803b7_8-1-scaled-355x229.jpg\" alt=\"\" width=\"355\" height=\"229\" \/><\/li><li><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.bonitastay.com\/wp-content\/uploads\/2024\/08\/382956_adafec8449_9-scaled-355x229.jpg\" alt=\"\" width=\"355\" height=\"229\" \/><\/li><li><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.bonitastay.com\/wp-content\/uploads\/2024\/08\/382956_99de5c2d5c_20-scaled-355x229.jpg\" alt=\"\" width=\"355\" height=\"229\" \/><\/li><li><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.bonitastay.com\/wp-content\/uploads\/2024\/08\/382956_1470d55322_4-1-scaled-355x229.jpg\" alt=\"\" width=\"355\" height=\"229\" \/><\/li><li><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.bonitastay.com\/wp-content\/uploads\/2024\/08\/382956_3482e5dc69_11-scaled-355x229.jpg\" alt=\"\" width=\"355\" height=\"229\" \/><\/li><li><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.bonitastay.com\/wp-content\/uploads\/2024\/08\/382956_9207dd264f_14-scaled-355x229.jpg\" alt=\"\" width=\"355\" height=\"229\" \/><\/li><li><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.bonitastay.com\/wp-content\/uploads\/2024\/08\/382956_4053451d61_15-scaled-355x229.jpg\" alt=\"\" width=\"355\" height=\"229\" \/><\/li><li><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.bonitastay.com\/wp-content\/uploads\/2024\/08\/382956_a46e5dec1f_22-scaled-355x229.jpg\" alt=\"\" width=\"355\" height=\"229\" \/><\/li><li><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.bonitastay.com\/wp-content\/uploads\/2024\/08\/382956_c5e808a405_23-scaled-355x229.jpg\" alt=\"\" width=\"355\" height=\"229\" \/><\/li><li><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.bonitastay.com\/wp-content\/uploads\/2024\/08\/382956_e9f90aa35f_10-scaled-355x229.jpg\" alt=\"\" width=\"355\" height=\"229\" \/><\/li><li><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.bonitastay.com\/wp-content\/uploads\/2024\/08\/382956_5ea865fe2c_21-scaled-355x229.jpg\" alt=\"\" width=\"355\" height=\"229\" \/><\/li><li><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.bonitastay.com\/wp-content\/uploads\/2024\/08\/382956_ef868f51e5_17-scaled-355x229.jpg\" alt=\"\" width=\"355\" height=\"229\" \/><\/li><li><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.bonitastay.com\/wp-content\/uploads\/2024\/08\/382956_eb97487ae4_18-scaled-355x229.jpg\" alt=\"\" width=\"355\" height=\"229\" \/><\/li><li><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.bonitastay.com\/wp-content\/uploads\/2024\/08\/382956_e883fca07b_16-scaled-355x229.jpg\" alt=\"\" width=\"355\" height=\"229\" \/><\/li><li><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.bonitastay.com\/wp-content\/uploads\/2024\/08\/382956_ae8aa05101_19-scaled-355x229.jpg\" alt=\"\" width=\"355\" height=\"229\" \/><\/li><\/div><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-24e22ab elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"24e22ab\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-house-user\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Capacity 6 people<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-bed\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">2 Bedrooms - 2 Bathrooms<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-swimming-pool\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Swimming pool<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-27980a3 elementor-widget elementor-widget-button\" data-id=\"27980a3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-xs\" href=\"https:\/\/bookonline.pro\/en\/property\/382956?guests=1\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">BOOK<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-63d9fa9\" data-id=\"63d9fa9\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a3b1011 elementor-widget elementor-widget-qi_addons_for_elementor_section_title\" data-id=\"a3b1011\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"qi_addons_for_elementor_section_title.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"qodef-shortcode qodef-m qodef-qi-section-title qodef-decoration--italic qodef-link--underline-draw qodef-subtitle-icon--left\">\n\t\t\t\t\t\t<h4 class=\"qodef-m-title\">\n\t\tJ\u00e1vea - B ROCKS\t<\/h4>\n\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9180aaa animated-slow elementor-invisible elementor-widget elementor-widget-bridge_image_gallery\" data-id=\"9180aaa\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeIn&quot;}\" data-widget_type=\"bridge_image_gallery.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"qode-image-gallery\"><div class=\"qode-image-gallery-inner\"><div class=\"qode-image-gallery-slides flexslider_slide flexslider\" data-interval=\"0\" data-flex_fx=\"slide\"data-control=\"false\"data-direction=\"true\"data-drag=\"false\"><ul class=\"slides\"><li><a itemprop=\"url\" href=\"https:\/\/bookonline.pro\/en\/property\/250039?guests=1\" target=\"_self\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.bonitastay.com\/wp-content\/uploads\/2023\/07\/25-3-355x229.png\" alt=\"\" width=\"355\" height=\"229\" \/><\/a><\/li><li><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.bonitastay.com\/wp-content\/uploads\/2023\/07\/1-3-355x229.png\" alt=\"\" width=\"355\" height=\"229\" \/><\/li><li><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.bonitastay.com\/wp-content\/uploads\/2023\/07\/2-3-355x229.png\" alt=\"\" width=\"355\" height=\"229\" \/><\/li><li><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.bonitastay.com\/wp-content\/uploads\/2023\/07\/3-3-355x229.png\" alt=\"\" width=\"355\" height=\"229\" \/><\/li><li><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.bonitastay.com\/wp-content\/uploads\/2023\/07\/4-3-355x229.png\" alt=\"\" width=\"355\" height=\"229\" \/><\/li><li><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.bonitastay.com\/wp-content\/uploads\/2023\/07\/5-3-355x229.png\" alt=\"\" width=\"355\" height=\"229\" \/><\/li><li><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.bonitastay.com\/wp-content\/uploads\/2023\/07\/6-3-355x229.png\" alt=\"\" width=\"355\" height=\"229\" \/><\/li><li><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.bonitastay.com\/wp-content\/uploads\/2023\/07\/7-3-355x229.png\" alt=\"\" width=\"355\" height=\"229\" \/><\/li><li><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.bonitastay.com\/wp-content\/uploads\/2023\/07\/8-3-355x229.png\" alt=\"\" width=\"355\" height=\"229\" \/><\/li><li><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.bonitastay.com\/wp-content\/uploads\/2023\/07\/9-3-355x229.png\" alt=\"\" width=\"355\" height=\"229\" \/><\/li><li><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.bonitastay.com\/wp-content\/uploads\/2023\/07\/10-3-355x229.png\" alt=\"\" width=\"355\" height=\"229\" \/><\/li><li><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.bonitastay.com\/wp-content\/uploads\/2023\/07\/11-3-355x229.png\" alt=\"\" width=\"355\" height=\"229\" \/><\/li><li><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.bonitastay.com\/wp-content\/uploads\/2023\/07\/12-3-355x229.png\" alt=\"\" width=\"355\" height=\"229\" \/><\/li><li><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.bonitastay.com\/wp-content\/uploads\/2023\/07\/13-3-355x229.png\" alt=\"\" width=\"355\" height=\"229\" \/><\/li><li><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.bonitastay.com\/wp-content\/uploads\/2023\/07\/14-3-355x229.png\" alt=\"\" width=\"355\" height=\"229\" \/><\/li><li><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.bonitastay.com\/wp-content\/uploads\/2023\/07\/15-3-355x229.png\" alt=\"\" width=\"355\" height=\"229\" \/><\/li><li><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.bonitastay.com\/wp-content\/uploads\/2023\/07\/16-3-355x229.png\" alt=\"\" width=\"355\" height=\"229\" \/><\/li><li><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.bonitastay.com\/wp-content\/uploads\/2023\/07\/17-3-355x229.png\" alt=\"\" width=\"355\" height=\"229\" \/><\/li><li><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.bonitastay.com\/wp-content\/uploads\/2023\/07\/18-3-355x229.png\" alt=\"\" width=\"355\" height=\"229\" \/><\/li><li><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.bonitastay.com\/wp-content\/uploads\/2023\/07\/19-3-355x229.png\" alt=\"\" width=\"355\" height=\"229\" \/><\/li><li><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.bonitastay.com\/wp-content\/uploads\/2023\/07\/20-3-355x229.png\" alt=\"\" width=\"355\" height=\"229\" \/><\/li><li><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.bonitastay.com\/wp-content\/uploads\/2023\/07\/21-3-355x229.png\" alt=\"\" width=\"355\" height=\"229\" \/><\/li><li><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.bonitastay.com\/wp-content\/uploads\/2023\/07\/22-3-355x229.png\" alt=\"\" width=\"355\" height=\"229\" \/><\/li><li><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.bonitastay.com\/wp-content\/uploads\/2023\/07\/23-3-355x229.png\" alt=\"\" width=\"355\" height=\"229\" \/><\/li><li><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.bonitastay.com\/wp-content\/uploads\/2023\/07\/24-3-355x229.png\" alt=\"\" width=\"355\" height=\"229\" \/><\/li><li><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.bonitastay.com\/wp-content\/uploads\/2023\/07\/26-3-355x229.png\" alt=\"\" width=\"355\" height=\"229\" \/><\/li><li><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.bonitastay.com\/wp-content\/uploads\/2023\/07\/27-2-355x229.png\" alt=\"\" width=\"355\" height=\"229\" \/><\/li><li><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.bonitastay.com\/wp-content\/uploads\/2023\/07\/28-3-355x229.png\" alt=\"\" width=\"355\" height=\"229\" \/><\/li><li><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.bonitastay.com\/wp-content\/uploads\/2023\/07\/29-3-355x229.png\" alt=\"\" width=\"355\" height=\"229\" \/><\/li><li><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.bonitastay.com\/wp-content\/uploads\/2023\/07\/30-3-355x229.png\" alt=\"\" width=\"355\" height=\"229\" \/><\/li><li><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.bonitastay.com\/wp-content\/uploads\/2023\/07\/31-3-355x229.png\" alt=\"\" width=\"355\" height=\"229\" \/><\/li><li><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.bonitastay.com\/wp-content\/uploads\/2023\/07\/32-3-355x229.png\" alt=\"\" width=\"355\" height=\"229\" \/><\/li><li><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.bonitastay.com\/wp-content\/uploads\/2023\/07\/33-3-355x229.png\" alt=\"\" width=\"355\" height=\"229\" \/><\/li><li><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.bonitastay.com\/wp-content\/uploads\/2023\/07\/34-3-355x229.png\" alt=\"\" width=\"355\" height=\"229\" \/><\/li><li><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.bonitastay.com\/wp-content\/uploads\/2023\/07\/35-3-355x229.png\" alt=\"\" width=\"355\" height=\"229\" \/><\/li><li><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.bonitastay.com\/wp-content\/uploads\/2023\/07\/36-3-355x229.png\" alt=\"\" width=\"355\" height=\"229\" \/><\/li><li><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.bonitastay.com\/wp-content\/uploads\/2023\/07\/37-3-355x229.png\" alt=\"\" width=\"355\" height=\"229\" \/><\/li><li><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.bonitastay.com\/wp-content\/uploads\/2023\/07\/38-3-355x229.png\" alt=\"\" width=\"355\" height=\"229\" \/><\/li><li><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.bonitastay.com\/wp-content\/uploads\/2023\/07\/39-3-355x229.png\" alt=\"\" width=\"355\" height=\"229\" \/><\/li><li><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.bonitastay.com\/wp-content\/uploads\/2023\/07\/40-3-355x229.png\" alt=\"\" width=\"355\" height=\"229\" \/><\/li><\/div><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-289b9a3 elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"289b9a3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-house-user\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Capacity 3 people<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-bed\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">1 Bedroom - 1 Bathroom<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-swimming-pool\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Swimming pool<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f45bc29 elementor-widget elementor-widget-button\" data-id=\"f45bc29\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-xs\" href=\"https:\/\/bookonline.pro\/en\/property\/250039?guests=1\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">BOOK<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-aa5f33e\" data-id=\"aa5f33e\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-2615af8 elementor-section-full_width qode_elementor_container_inner elementor-section-height-default elementor-section-height-default parallax_section_no\" data-id=\"2615af8\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;animation&quot;:&quot;none&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-1ce1aa0\" data-id=\"1ce1aa0\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1f14d09 elementor-widget elementor-widget-qi_addons_for_elementor_section_title\" data-id=\"1f14d09\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"qi_addons_for_elementor_section_title.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"qodef-shortcode qodef-m qodef-qi-section-title qodef-decoration--italic qodef-link--underline-draw qodef-subtitle-icon--left\">\n\t\t\t\t\t\t<h4 class=\"qodef-m-title\">\n\t\tDenia - B BEACH\t<\/h4>\n\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8f9a615 elementor-widget elementor-widget-bridge_image_gallery\" data-id=\"8f9a615\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"bridge_image_gallery.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"qode-image-gallery\"><div class=\"qode-image-gallery-inner\"><div class=\"qode-image-gallery-slides flexslider_slide flexslider\" data-interval=\"0\" data-flex_fx=\"slide\"data-control=\"false\"data-direction=\"true\"data-drag=\"false\"><ul class=\"slides\"><li><a itemprop=\"url\" href=\"https:\/\/bookonline.pro\/en\/property\/250041?guests=1\" target=\"_self\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.bonitastay.com\/wp-content\/uploads\/2024\/11\/384813_6f41ba61c4_2-2-scaled-355x229.jpg\" alt=\"\" width=\"355\" height=\"229\" \/><\/a><\/li><li><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.bonitastay.com\/wp-content\/uploads\/2024\/11\/384813_e51bb4b9bb_3-scaled-355x229.jpg\" alt=\"\" width=\"355\" height=\"229\" \/><\/li><li><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.bonitastay.com\/wp-content\/uploads\/2024\/11\/384813_ffaf9bce9b_44-scaled-355x229.jpg\" alt=\"\" width=\"355\" height=\"229\" \/><\/li><li><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.bonitastay.com\/wp-content\/uploads\/2024\/11\/384813_97ac21e6f9_7-scaled-355x229.jpg\" alt=\"\" width=\"355\" height=\"229\" \/><\/li><li><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.bonitastay.com\/wp-content\/uploads\/2024\/11\/384813_c1d341c84b_5-scaled-355x229.jpg\" alt=\"\" width=\"355\" height=\"229\" \/><\/li><li><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.bonitastay.com\/wp-content\/uploads\/2024\/11\/384813_96cdd5fef2_6-scaled-355x229.jpg\" alt=\"\" width=\"355\" height=\"229\" \/><\/li><li><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.bonitastay.com\/wp-content\/uploads\/2024\/11\/384813_43a9ec2aff_4-scaled-355x229.jpg\" alt=\"\" width=\"355\" height=\"229\" \/><\/li><li><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.bonitastay.com\/wp-content\/uploads\/2024\/11\/384813_5a92f07943_8-scaled-355x229.jpg\" alt=\"\" width=\"355\" height=\"229\" \/><\/li><li><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.bonitastay.com\/wp-content\/uploads\/2024\/11\/384813_77a4b20562_9-scaled-355x229.jpg\" alt=\"\" width=\"355\" height=\"229\" \/><\/li><li><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.bonitastay.com\/wp-content\/uploads\/2024\/11\/384813_f9fa021d9d_11-scaled-355x229.jpg\" alt=\"\" width=\"355\" height=\"229\" \/><\/li><li><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.bonitastay.com\/wp-content\/uploads\/2024\/11\/384813_4d8f380b1e_10-scaled-355x229.jpg\" alt=\"\" width=\"355\" height=\"229\" \/><\/li><li><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.bonitastay.com\/wp-content\/uploads\/2024\/11\/384813_f5aba03e21_33-scaled-355x229.jpg\" alt=\"\" width=\"355\" height=\"229\" \/><\/li><li><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.bonitastay.com\/wp-content\/uploads\/2024\/11\/384813_c645683784_18-scaled-355x229.jpg\" alt=\"\" width=\"355\" height=\"229\" \/><\/li><li><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.bonitastay.com\/wp-content\/uploads\/2024\/11\/384813_c97e4bdeb4_12-scaled-355x229.jpg\" alt=\"\" width=\"355\" height=\"229\" \/><\/li><li><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.bonitastay.com\/wp-content\/uploads\/2024\/11\/384813_fbab9f1b1c_15-scaled-355x229.jpg\" alt=\"\" width=\"355\" height=\"229\" \/><\/li><li><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.bonitastay.com\/wp-content\/uploads\/2024\/11\/384813_cdf42fa41b_23-scaled-355x229.jpg\" alt=\"\" width=\"355\" height=\"229\" \/><\/li><li><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.bonitastay.com\/wp-content\/uploads\/2024\/11\/384813_be793695ef_14-scaled-355x229.jpg\" alt=\"\" width=\"355\" height=\"229\" \/><\/li><li><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.bonitastay.com\/wp-content\/uploads\/2024\/11\/384813_bcdbb19143_17-scaled-355x229.jpg\" alt=\"\" width=\"355\" height=\"229\" \/><\/li><li><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.bonitastay.com\/wp-content\/uploads\/2024\/11\/384813_2939694f52_22-scaled-355x229.jpg\" alt=\"\" width=\"355\" height=\"229\" \/><\/li><li><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.bonitastay.com\/wp-content\/uploads\/2024\/11\/384813_00419fe2f1_20-scaled-355x229.jpg\" alt=\"\" width=\"355\" height=\"229\" \/><\/li><li><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.bonitastay.com\/wp-content\/uploads\/2024\/11\/384813_93adfe4c04_19-scaled-355x229.jpg\" alt=\"\" width=\"355\" height=\"229\" \/><\/li><li><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.bonitastay.com\/wp-content\/uploads\/2024\/11\/384813_56f229fb1c_21-scaled-355x229.jpg\" alt=\"\" width=\"355\" height=\"229\" \/><\/li><li><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.bonitastay.com\/wp-content\/uploads\/2024\/11\/384813_71c2401995_13-scaled-355x229.jpg\" alt=\"\" width=\"355\" height=\"229\" \/><\/li><li><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.bonitastay.com\/wp-content\/uploads\/2024\/11\/384813_9dc0d76e4b_16-scaled-355x229.jpg\" alt=\"\" width=\"355\" height=\"229\" \/><\/li><li><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.bonitastay.com\/wp-content\/uploads\/2024\/11\/384813_6e567f14fc_30-scaled-355x229.jpg\" alt=\"\" width=\"355\" height=\"229\" \/><\/li><li><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.bonitastay.com\/wp-content\/uploads\/2024\/11\/384813_c20028eaf1_31-scaled-355x229.jpg\" alt=\"\" width=\"355\" height=\"229\" \/><\/li><li><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.bonitastay.com\/wp-content\/uploads\/2024\/11\/384813_c0cddba5e1_27-scaled-355x229.jpg\" alt=\"\" width=\"355\" height=\"229\" \/><\/li><li><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.bonitastay.com\/wp-content\/uploads\/2024\/11\/384813_f8c4083a43_29-scaled-355x229.jpg\" alt=\"\" width=\"355\" height=\"229\" \/><\/li><li><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.bonitastay.com\/wp-content\/uploads\/2024\/11\/384813_85bb8f1b48_28-scaled-355x229.jpg\" alt=\"\" width=\"355\" height=\"229\" \/><\/li><li><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.bonitastay.com\/wp-content\/uploads\/2024\/11\/384813_30ddb5622e_26-scaled-355x229.jpg\" alt=\"\" width=\"355\" height=\"229\" \/><\/li><li><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.bonitastay.com\/wp-content\/uploads\/2024\/11\/384813_801baeddef_41-scaled-355x229.jpg\" alt=\"\" width=\"355\" height=\"229\" \/><\/li><li><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.bonitastay.com\/wp-content\/uploads\/2024\/11\/384813_78137481de_35-scaled-355x229.jpg\" alt=\"\" width=\"355\" height=\"229\" \/><\/li><li><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.bonitastay.com\/wp-content\/uploads\/2024\/11\/384813_3f5838482a_34-scaled-355x229.jpg\" alt=\"\" width=\"355\" height=\"229\" \/><\/li><li><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.bonitastay.com\/wp-content\/uploads\/2024\/11\/384813_913663f23e_24-scaled-355x229.jpg\" alt=\"\" width=\"355\" height=\"229\" \/><\/li><li><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.bonitastay.com\/wp-content\/uploads\/2024\/11\/384813_11cf1c9a9b_25-scaled-355x229.jpg\" alt=\"\" width=\"355\" height=\"229\" \/><\/li><li><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.bonitastay.com\/wp-content\/uploads\/2024\/11\/384813_87cfd50896_40-scaled-355x229.jpg\" alt=\"\" width=\"355\" height=\"229\" \/><\/li><li><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.bonitastay.com\/wp-content\/uploads\/2024\/11\/384813_99d406f550_39-scaled-355x229.jpg\" alt=\"\" width=\"355\" height=\"229\" \/><\/li><li><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.bonitastay.com\/wp-content\/uploads\/2024\/11\/384813_4260d1ec91_42-scaled-355x229.jpg\" alt=\"\" width=\"355\" height=\"229\" \/><\/li><li><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.bonitastay.com\/wp-content\/uploads\/2024\/11\/384813_85acc29238_29-scaled-355x229.jpg\" alt=\"\" width=\"355\" height=\"229\" \/><\/li><li><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.bonitastay.com\/wp-content\/uploads\/2024\/11\/384813_fe29389d4a_46-scaled-355x229.jpg\" alt=\"\" width=\"355\" height=\"229\" \/><\/li><li><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.bonitastay.com\/wp-content\/uploads\/2024\/11\/384813_0737221c08_37-scaled-355x229.jpg\" alt=\"\" width=\"355\" height=\"229\" \/><\/li><li><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.bonitastay.com\/wp-content\/uploads\/2024\/11\/384813_4c16302c10_43-scaled-355x229.jpg\" alt=\"\" width=\"355\" height=\"229\" \/><\/li><li><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.bonitastay.com\/wp-content\/uploads\/2024\/11\/384813_1a5c9631d5_45-scaled-355x229.jpg\" alt=\"\" width=\"355\" height=\"229\" \/><\/li><li><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.bonitastay.com\/wp-content\/uploads\/2024\/11\/384813_49ab9b133f_48-scaled-355x229.jpg\" alt=\"\" width=\"355\" height=\"229\" \/><\/li><li><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.bonitastay.com\/wp-content\/uploads\/2024\/11\/384813_0edf26bf89_47-scaled-355x229.jpg\" alt=\"\" width=\"355\" height=\"229\" \/><\/li><li><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.bonitastay.com\/wp-content\/uploads\/2024\/11\/384813_e359e709bd_36-scaled-355x229.jpg\" alt=\"\" width=\"355\" height=\"229\" \/><\/li><li><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.bonitastay.com\/wp-content\/uploads\/2024\/11\/384813_6d3816bce7_49-scaled-355x229.jpg\" alt=\"\" width=\"355\" height=\"229\" \/><\/li><li><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.bonitastay.com\/wp-content\/uploads\/2024\/11\/384813_d8b87534f9_1-scaled-355x229.jpg\" alt=\"\" width=\"355\" height=\"229\" \/><\/li><\/div><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c088aaa elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"c088aaa\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-house-user\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Capacity 10 people<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-bed\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">4 Bedrooms - 2 Bathrooms<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-swimming-pool\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Swimming pool<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1111183 elementor-widget elementor-widget-button\" data-id=\"1111183\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-xs\" href=\"https:\/\/bookonline.pro\/en\/property\/384813?guests=1\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">BOOK<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-3e6f61d\" data-id=\"3e6f61d\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-21e7ab1 elementor-widget elementor-widget-qi_addons_for_elementor_section_title\" data-id=\"21e7ab1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"qi_addons_for_elementor_section_title.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"qodef-shortcode qodef-m qodef-qi-section-title qodef-decoration--italic qodef-link--underline-draw qodef-subtitle-icon--left\">\n\t\t\t\t\t\t<h4 class=\"qodef-m-title\">\n\t\tDenia - B PALM\t<\/h4>\n\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9dea0a8 animated-slow elementor-invisible elementor-widget elementor-widget-bridge_image_gallery\" data-id=\"9dea0a8\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeIn&quot;}\" data-widget_type=\"bridge_image_gallery.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"qode-image-gallery\"><div class=\"qode-image-gallery-inner\"><div class=\"qode-image-gallery-slides flexslider_slide flexslider\" data-interval=\"0\" data-flex_fx=\"slide\"data-control=\"false\"data-direction=\"true\"data-drag=\"false\"><ul class=\"slides\"><li><a itemprop=\"url\" href=\"https:\/\/bookonline.pro\/en\/property\/250039?guests=1\" target=\"_self\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.bonitastay.com\/wp-content\/uploads\/2026\/04\/Riu-Cervol-8-1-scaled-355x229.jpg\" alt=\"\" width=\"355\" height=\"229\" \/><\/a><\/li><li><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.bonitastay.com\/wp-content\/uploads\/2026\/04\/Riu-Cervol-8-2-scaled-355x229.jpg\" alt=\"\" width=\"355\" height=\"229\" \/><\/li><li><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.bonitastay.com\/wp-content\/uploads\/2026\/04\/Riu-Cervol-8-3-scaled-355x229.jpg\" alt=\"\" width=\"355\" height=\"229\" \/><\/li><li><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.bonitastay.com\/wp-content\/uploads\/2026\/04\/Riu-Cervol-8-4-scaled-355x229.jpg\" alt=\"\" width=\"355\" height=\"229\" \/><\/li><li><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.bonitastay.com\/wp-content\/uploads\/2026\/04\/Riu-Cervol-8-5-scaled-355x229.jpg\" alt=\"\" width=\"355\" height=\"229\" \/><\/li><li><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.bonitastay.com\/wp-content\/uploads\/2026\/04\/Riu-Cervol-8-6-scaled-355x229.jpg\" alt=\"\" width=\"355\" height=\"229\" \/><\/li><li><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.bonitastay.com\/wp-content\/uploads\/2026\/04\/Riu-Cervol-8-7-scaled-355x229.jpg\" alt=\"\" width=\"355\" height=\"229\" \/><\/li><li><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.bonitastay.com\/wp-content\/uploads\/2026\/04\/Riu-Cervol-8-8-scaled-355x229.jpg\" alt=\"\" width=\"355\" height=\"229\" \/><\/li><li><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.bonitastay.com\/wp-content\/uploads\/2026\/04\/Riu-Cervol-8-9-scaled-355x229.jpg\" alt=\"\" width=\"355\" height=\"229\" \/><\/li><li><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.bonitastay.com\/wp-content\/uploads\/2026\/04\/Riu-Cervol-8-10-scaled-355x229.jpg\" alt=\"\" width=\"355\" height=\"229\" \/><\/li><li><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.bonitastay.com\/wp-content\/uploads\/2026\/04\/Riu-Cervol-8-11-scaled-355x229.jpg\" alt=\"\" width=\"355\" height=\"229\" \/><\/li><li><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.bonitastay.com\/wp-content\/uploads\/2026\/04\/Riu-Cervol-8-13-scaled-355x229.jpg\" alt=\"\" width=\"355\" height=\"229\" \/><\/li><li><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.bonitastay.com\/wp-content\/uploads\/2026\/04\/Riu-Cervol-8-14-scaled-355x229.jpg\" alt=\"\" width=\"355\" height=\"229\" \/><\/li><li><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.bonitastay.com\/wp-content\/uploads\/2026\/04\/Riu-Cervol-8-15-scaled-355x229.jpg\" alt=\"\" width=\"355\" height=\"229\" \/><\/li><li><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.bonitastay.com\/wp-content\/uploads\/2026\/04\/Riu-Cervol-8-16-scaled-355x229.jpg\" alt=\"\" width=\"355\" height=\"229\" \/><\/li><li><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.bonitastay.com\/wp-content\/uploads\/2026\/04\/Riu-Cervol-8-17-scaled-355x229.jpg\" alt=\"\" width=\"355\" height=\"229\" \/><\/li><li><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.bonitastay.com\/wp-content\/uploads\/2026\/04\/Riu-Cervol-8-18-scaled-355x229.jpg\" alt=\"\" width=\"355\" height=\"229\" \/><\/li><li><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.bonitastay.com\/wp-content\/uploads\/2026\/04\/Riu-Cervol-8-19-scaled-355x229.jpg\" alt=\"\" width=\"355\" height=\"229\" \/><\/li><li><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.bonitastay.com\/wp-content\/uploads\/2026\/04\/Riu-Cervol-8-20-scaled-355x229.jpg\" alt=\"\" width=\"355\" height=\"229\" \/><\/li><li><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.bonitastay.com\/wp-content\/uploads\/2026\/04\/Riu-Cervol-8-21-scaled-355x229.jpg\" alt=\"\" width=\"355\" height=\"229\" \/><\/li><li><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.bonitastay.com\/wp-content\/uploads\/2026\/04\/Riu-Cervol-8-22-scaled-355x229.jpg\" alt=\"\" width=\"355\" height=\"229\" \/><\/li><li><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.bonitastay.com\/wp-content\/uploads\/2026\/04\/Riu-Cervol-8-23-scaled-355x229.jpg\" alt=\"\" width=\"355\" height=\"229\" \/><\/li><li><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.bonitastay.com\/wp-content\/uploads\/2026\/04\/Riu-Cervol-8-24-scaled-355x229.jpg\" alt=\"\" width=\"355\" height=\"229\" \/><\/li><li><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.bonitastay.com\/wp-content\/uploads\/2026\/04\/Riu-Cervol-8-25-scaled-355x229.jpg\" alt=\"\" width=\"355\" height=\"229\" \/><\/li><li><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.bonitastay.com\/wp-content\/uploads\/2026\/04\/Riu-Cervol-8-26-scaled-355x229.jpg\" alt=\"\" width=\"355\" height=\"229\" \/><\/li><li><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.bonitastay.com\/wp-content\/uploads\/2026\/04\/Riu-Cervol-8-27-scaled-355x229.jpg\" alt=\"\" width=\"355\" height=\"229\" \/><\/li><li><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.bonitastay.com\/wp-content\/uploads\/2026\/04\/Riu-Cervol-8-28-scaled-355x229.jpg\" alt=\"\" width=\"355\" height=\"229\" \/><\/li><li><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.bonitastay.com\/wp-content\/uploads\/2026\/04\/Riu-Cervol-8-32-scaled-355x229.jpg\" alt=\"\" width=\"355\" height=\"229\" \/><\/li><li><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.bonitastay.com\/wp-content\/uploads\/2026\/04\/Riu-Cervol-8-33-scaled-355x229.jpg\" alt=\"\" width=\"355\" height=\"229\" \/><\/li><li><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.bonitastay.com\/wp-content\/uploads\/2026\/04\/Riu-Cervol-8-34-scaled-355x229.jpg\" alt=\"\" width=\"355\" height=\"229\" \/><\/li><li><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.bonitastay.com\/wp-content\/uploads\/2026\/04\/Riu-Cervol-8-35-scaled-355x229.jpg\" alt=\"\" width=\"355\" height=\"229\" \/><\/li><li><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.bonitastay.com\/wp-content\/uploads\/2026\/04\/Riu-Cervol-8-36-scaled-355x229.jpg\" alt=\"\" width=\"355\" height=\"229\" \/><\/li><li><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.bonitastay.com\/wp-content\/uploads\/2026\/04\/Riu-Cervol-8-37-scaled-355x229.jpg\" alt=\"\" width=\"355\" height=\"229\" \/><\/li><li><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.bonitastay.com\/wp-content\/uploads\/2026\/04\/Riu-Cervol-8-38-scaled-355x229.jpg\" alt=\"\" width=\"355\" height=\"229\" \/><\/li><li><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.bonitastay.com\/wp-content\/uploads\/2026\/04\/Riu-Cervol-8-39-scaled-355x229.jpg\" alt=\"\" width=\"355\" height=\"229\" \/><\/li><li><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.bonitastay.com\/wp-content\/uploads\/2026\/04\/Riu-Cervol-8-40-scaled-355x229.jpg\" alt=\"\" width=\"355\" height=\"229\" \/><\/li><li><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.bonitastay.com\/wp-content\/uploads\/2026\/04\/Riu-Cervol-8-41-scaled-355x229.jpg\" alt=\"\" width=\"355\" height=\"229\" \/><\/li><li><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.bonitastay.com\/wp-content\/uploads\/2026\/04\/Riu-Cervol-8-42-scaled-355x229.jpg\" alt=\"\" width=\"355\" height=\"229\" \/><\/li><li><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.bonitastay.com\/wp-content\/uploads\/2026\/04\/Riu-Cervol-8-43-scaled-355x229.jpg\" alt=\"\" width=\"355\" height=\"229\" \/><\/li><li><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.bonitastay.com\/wp-content\/uploads\/2026\/04\/Riu-Cervol-8-44-scaled-355x229.jpg\" alt=\"\" width=\"355\" height=\"229\" \/><\/li><li><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.bonitastay.com\/wp-content\/uploads\/2026\/04\/Riu-Cervol-8-45-scaled-355x229.jpg\" alt=\"\" width=\"355\" height=\"229\" \/><\/li><li><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.bonitastay.com\/wp-content\/uploads\/2026\/04\/Riu-Cervol-8-46-scaled-355x229.jpg\" alt=\"\" width=\"355\" height=\"229\" \/><\/li><li><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.bonitastay.com\/wp-content\/uploads\/2026\/04\/Riu-Cervol-8-47-scaled-355x229.jpg\" alt=\"\" width=\"355\" height=\"229\" \/><\/li><li><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.bonitastay.com\/wp-content\/uploads\/2026\/04\/Riu-Cervol-8-48-scaled-355x229.jpg\" alt=\"\" width=\"355\" height=\"229\" \/><\/li><li><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.bonitastay.com\/wp-content\/uploads\/2026\/04\/Riu-Cervol-8-50-scaled-355x229.jpg\" alt=\"\" width=\"355\" height=\"229\" \/><\/li><li><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.bonitastay.com\/wp-content\/uploads\/2026\/04\/zz-Riu-Cervol-8-12-scaled-355x229.jpg\" alt=\"\" width=\"355\" height=\"229\" \/><\/li><\/div><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-cabed5e elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"cabed5e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-house-user\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Capacity 10 people<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-bed\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">4 Bedrooms - 2 Bathrooms<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-swimming-pool\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Swimming pool<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6483764 elementor-widget elementor-widget-button\" data-id=\"6483764\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-xs\" href=\"https:\/\/bookonline.pro\/en\/property\/401572?guests=1\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">BOOK<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-b617e23\" data-id=\"b617e23\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-336477c elementor-section-full_width qode_elementor_container_inner elementor-section-height-default elementor-section-height-default parallax_section_no\" data-id=\"336477c\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;animation&quot;:&quot;none&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-2f5031a\" data-id=\"2f5031a\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ab0cfdb elementor-widget elementor-widget-qi_addons_for_elementor_section_title\" data-id=\"ab0cfdb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"qi_addons_for_elementor_section_title.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"qodef-shortcode qodef-m qodef-qi-section-title qodef-decoration--italic qodef-link--underline-draw qodef-subtitle-icon--left\">\n\t\t\t\t\t\t<h4 class=\"qodef-m-title\">\n\t\tPanticosa - B PAZ\t<\/h4>\n\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-042aad0 elementor-widget elementor-widget-bridge_image_gallery\" data-id=\"042aad0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"bridge_image_gallery.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"qode-image-gallery\"><div class=\"qode-image-gallery-inner\"><div class=\"qode-image-gallery-slides flexslider_slide flexslider\" data-interval=\"0\" data-flex_fx=\"slide\"data-control=\"false\"data-direction=\"true\"data-drag=\"false\"><ul class=\"slides\"><li><a itemprop=\"url\" href=\"https:\/\/bookonline.pro\/en\/property\/250041?guests=1\" target=\"_self\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.bonitastay.com\/wp-content\/uploads\/2025\/09\/250041_5e11b4c86e_1-1-355x229.jpg\" alt=\"\" width=\"355\" height=\"229\" \/><\/a><\/li><li><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.bonitastay.com\/wp-content\/uploads\/2023\/06\/Diseno-sin-titulo-49-355x229.png\" alt=\"\" width=\"355\" height=\"229\" \/><\/li><li><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.bonitastay.com\/wp-content\/uploads\/2023\/06\/bPaz_7-355x229.jpg\" alt=\"\" width=\"355\" height=\"229\" \/><\/li><li><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.bonitastay.com\/wp-content\/uploads\/2023\/06\/Diseno-sin-titulo-51-355x229.png\" alt=\"\" width=\"355\" height=\"229\" \/><\/li><li><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.bonitastay.com\/wp-content\/uploads\/2023\/06\/1-355x229.png\" alt=\"\" width=\"355\" height=\"229\" \/><\/li><li><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.bonitastay.com\/wp-content\/uploads\/2023\/06\/bPaz_4-355x229.jpg\" alt=\"\" width=\"355\" height=\"229\" \/><\/li><li><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.bonitastay.com\/wp-content\/uploads\/2023\/06\/Diseno-sin-titulo-52-355x229.png\" alt=\"\" width=\"355\" height=\"229\" \/><\/li><li><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.bonitastay.com\/wp-content\/uploads\/2023\/06\/bPaz_2-355x229.jpg\" alt=\"\" width=\"355\" height=\"229\" \/><\/li><li><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.bonitastay.com\/wp-content\/uploads\/2023\/06\/bPaz_1-355x229.jpg\" alt=\"\" width=\"355\" height=\"229\" \/><\/li><li><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.bonitastay.com\/wp-content\/uploads\/2023\/06\/bPaz_9-355x229.jpg\" alt=\"\" width=\"355\" height=\"229\" \/><\/li><\/div><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ca67fcc elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"ca67fcc\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-house-user\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Capacity 14 people<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-bed\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">5 Bedrooms - 2 Bathrooms<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-swimming-pool\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Swimming pool<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d931e62 elementor-widget elementor-widget-button\" data-id=\"d931e62\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-xs\" href=\"https:\/\/bookonline.pro\/en\/property\/250041?guests=1\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">BOOK<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-c90793c\" data-id=\"c90793c\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-08782de elementor-widget elementor-widget-qi_addons_for_elementor_section_title\" data-id=\"08782de\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"qi_addons_for_elementor_section_title.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"qodef-shortcode qodef-m qodef-qi-section-title qodef-decoration--italic qodef-link--underline-draw qodef-subtitle-icon--left\">\n\t\t\t\t\t\t<h4 class=\"qodef-m-title\">\n\t\tAlways available for you\t<\/h4>\n\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-acd3331 elementor-widget elementor-widget-image\" data-id=\"acd3331\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"691\" height=\"461\" src=\"https:\/\/www.bonitastay.com\/wp-content\/uploads\/2024\/05\/BROCKS-Formato-WEB-691-\u00d7-461-px-691-\u00d7-461-px-691-\u00d7-461-px-1.png\" class=\"attachment-large size-large wp-image-5001\" alt=\"\" srcset=\"https:\/\/www.bonitastay.com\/wp-content\/uploads\/2024\/05\/BROCKS-Formato-WEB-691-\u00d7-461-px-691-\u00d7-461-px-691-\u00d7-461-px-1.png 691w, https:\/\/www.bonitastay.com\/wp-content\/uploads\/2024\/05\/BROCKS-Formato-WEB-691-\u00d7-461-px-691-\u00d7-461-px-691-\u00d7-461-px-1-300x200.png 300w\" sizes=\"(max-width: 691px) 100vw, 691px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-90c0239\" data-id=\"90c0239\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-678e222 elementor-widget elementor-widget-qi_addons_for_elementor_section_title\" data-id=\"678e222\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"qi_addons_for_elementor_section_title.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"qodef-shortcode qodef-m qodef-qi-section-title qodef-decoration--italic qodef-link--underline-draw qodef-subtitle-icon--left\">\n\t\t\t\t\t\t<h4 class=\"qodef-m-title\">\n\t\t \t<\/h4>\n\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-17d6dd0 animated-slow elementor-section-boxed elementor-section-height-default elementor-section-height-default parallax_section_no qode_elementor_container_no\" data-id=\"17d6dd0\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;slideshow&quot;,&quot;background_slideshow_gallery&quot;:[{&quot;id&quot;:3153,&quot;url&quot;:&quot;https:\\\/\\\/www.bonitastay.com\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/banner_eco2.jpg&quot;}],&quot;animation&quot;:&quot;none&quot;,&quot;background_slideshow_loop&quot;:&quot;yes&quot;,&quot;background_slideshow_slide_duration&quot;:5000,&quot;background_slideshow_slide_transition&quot;:&quot;fade&quot;,&quot;background_slideshow_transition_duration&quot;:500}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-be08957\" data-id=\"be08957\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-6374d5f0 elementor-section-boxed elementor-section-height-default elementor-section-height-default parallax_section_no qode_elementor_container_no\" data-id=\"6374d5f0\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;animation&quot;:&quot;none&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-da07d5f\" data-id=\"da07d5f\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-666b9684\" data-id=\"666b9684\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-72fd784c elementor-widget elementor-widget-heading\" data-id=\"72fd784c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">SUSTAINABLE HOMES<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-10ea33b6 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"10ea33b6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-2b59d35\" data-id=\"2b59d35\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-26ab168 elementor-hidden-mobile elementor-section-boxed elementor-section-height-default elementor-section-height-default parallax_section_no qode_elementor_container_no\" data-id=\"26ab168\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;animation&quot;:&quot;none&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-38149b9\" data-id=\"38149b9\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-cea5595 elementor-widget elementor-widget-bridge_icon_text\" data-id=\"cea5595\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"bridge_icon_text.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class='q_icon_with_title medium normal_icon '><div class=\"icon_holder \" style=\" \"><span data-icon-type=\"normal\"   style=\"\" class=\"qode_iwt_icon_holder q_font_awsome_icon fa-3x  \"><i class=\"qode_icon_font_awesome fa  qode_iwt_icon_element\" style=\"\" ><\/i><\/span><\/div><div class=\"icon_text_holder\" style=\"\"><div class=\"icon_text_inner\" style=\"\"><h5 class=\"icon_title\" style=\"\">Sustainable Materials<\/h5><p style=''>  We use natural and sustainable materials in our houses such as stone, cork, wood, ceramic bricks, tiles, granite, water-based paints.<\/p><\/div><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-2e89ad3\" data-id=\"2e89ad3\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-09f1933 elementor-widget elementor-widget-bridge_icon_text\" data-id=\"09f1933\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"bridge_icon_text.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class='q_icon_with_title medium normal_icon '><div class=\"icon_holder \" style=\" \"><span data-icon-type=\"normal\"   style=\"\" class=\"qode_iwt_icon_holder q_font_awsome_icon fa-3x  \"><i class=\"qode_icon_font_awesome fa  qode_iwt_icon_element\" style=\"\" ><\/i><\/span><\/div><div class=\"icon_text_holder\" style=\"\"><div class=\"icon_text_inner\" style=\"\"><h5 class=\"icon_title\" style=\"\">Energy Efficiency<\/h5><p style=''>We design all our accommodations from an efficient approach. Seeking sustainable energy consumption for the planet. BSky has an organic vegetable garden that is irrigated with rainwater.  <\/p><\/div><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-864d63c elementor-hidden-mobile elementor-section-boxed elementor-section-height-default elementor-section-height-default parallax_section_no qode_elementor_container_no\" data-id=\"864d63c\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;animation&quot;:&quot;none&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-c2e7ab0\" data-id=\"c2e7ab0\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-865be38 elementor-widget elementor-widget-bridge_icon_text\" data-id=\"865be38\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"bridge_icon_text.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class='q_icon_with_title medium normal_icon '><div class=\"icon_holder \" style=\" \"><span data-icon-type=\"normal\"   style=\"\" class=\"qode_iwt_icon_holder q_font_awsome_icon fa-3x  \"><i class=\"qode_icon_font_awesome fa  qode_iwt_icon_element\" style=\"\" ><\/i><\/span><\/div><div class=\"icon_text_holder\" style=\"\"><div class=\"icon_text_inner\" style=\"\"><h5 class=\"icon_title\" style=\"\">Electricity with Solar Panels<\/h5><p style=''>All the electrical energy you will use in our homes comes from renewable energy sources. It is generated by remote solar panels.<\/p><\/div><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-2f544ed\" data-id=\"2f544ed\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ec2caa8 elementor-widget elementor-widget-bridge_icon_text\" data-id=\"ec2caa8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"bridge_icon_text.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class='q_icon_with_title medium normal_icon '><div class=\"icon_holder \" style=\" \"><span data-icon-type=\"normal\"   style=\"\" class=\"qode_iwt_icon_holder q_font_awsome_icon fa-3x  \"><i class=\"qode_icon_font_awesome fa  qode_iwt_icon_element\" style=\"\" ><\/i><\/span><\/div><div class=\"icon_text_holder\" style=\"\"><div class=\"icon_text_inner\" style=\"\"><h5 class=\"icon_title\" style=\"\">Recycling Systems<\/h5><p style=''>We have recycling systems at each of our locations to facilitate waste recycling as part of our commitment to sustainability.<\/p><\/div><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-ad384c4 elementor-hidden-desktop elementor-hidden-tablet elementor-section-boxed elementor-section-height-default elementor-section-height-default parallax_section_no qode_elementor_container_no elementor-invisible\" data-id=\"ad384c4\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;animation&quot;:&quot;fadeInUp&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-ba40840\" data-id=\"ba40840\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c81a09b elementor-widget elementor-widget-bridge_icon_text\" data-id=\"c81a09b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"bridge_icon_text.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class='q_icon_with_title medium normal_icon '><div class=\"icon_holder \" style=\" \"><span data-icon-type=\"normal\"   style=\"\" class=\"qode_iwt_icon_holder q_font_awsome_icon fa-3x  \"><i class=\"qode_icon_font_awesome fa  qode_iwt_icon_element\" style=\"\" ><\/i><\/span><\/div><div class=\"icon_text_holder\" style=\"\"><div class=\"icon_text_inner\" style=\"\"><h5 class=\"icon_title\" style=\"\">Sustainable Materials<\/h5><div class=\"separator small left\" style=\"height: 2px;width: 20px;margin-bottom: 15px;\"><\/div><p style=''>  We use natural and sustainable materials in our houses such as stone, cork, wood, ceramic bricks, tiles, granite, water-based paints.<\/p><\/div><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-9c844fd\" data-id=\"9c844fd\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-48be963 elementor-widget elementor-widget-bridge_icon_text\" data-id=\"48be963\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"bridge_icon_text.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class='q_icon_with_title medium normal_icon '><div class=\"icon_holder \" style=\" \"><span data-icon-type=\"normal\"   style=\"\" class=\"qode_iwt_icon_holder q_font_awsome_icon fa-3x  \"><i class=\"qode_icon_font_awesome fa  qode_iwt_icon_element\" style=\"\" ><\/i><\/span><\/div><div class=\"icon_text_holder\" style=\"\"><div class=\"icon_text_inner\" style=\"\"><h5 class=\"icon_title\" style=\"\">Energy Efficiency<\/h5><div class=\"separator small left\" style=\"height: 2px;width: 20px;margin-bottom: 15px;\"><\/div><p style=''>We design all our accommodations from an efficient approach. Seeking sustainable energy consumption for the planet. BSky has an organic vegetable garden that is irrigated with rainwater.  <\/p><\/div><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-04cc6ff elementor-hidden-desktop elementor-hidden-tablet elementor-section-boxed elementor-section-height-default elementor-section-height-default parallax_section_no qode_elementor_container_no elementor-invisible\" data-id=\"04cc6ff\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;animation&quot;:&quot;fadeInUp&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-f297fe8\" data-id=\"f297fe8\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-dbf2425 elementor-widget elementor-widget-bridge_icon_text\" data-id=\"dbf2425\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"bridge_icon_text.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class='q_icon_with_title medium normal_icon '><div class=\"icon_holder \" style=\" \"><span data-icon-type=\"normal\"   style=\"\" class=\"qode_iwt_icon_holder q_font_awsome_icon fa-3x  \"><i class=\"qode_icon_font_awesome fa  qode_iwt_icon_element\" style=\"\" ><\/i><\/span><\/div><div class=\"icon_text_holder\" style=\"\"><div class=\"icon_text_inner\" style=\"\"><h5 class=\"icon_title\" style=\"\">Electricity with Solar Panels<\/h5><div class=\"separator small left\" style=\"height: 2px;width: 20px;margin-bottom: 15px;\"><\/div><p style=''>All the electrical energy you will use in our homes comes from renewable energy sources. It is generated by remote solar panels.<\/p><\/div><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-ae160d0\" data-id=\"ae160d0\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5425da4 elementor-widget elementor-widget-bridge_icon_text\" data-id=\"5425da4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"bridge_icon_text.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class='q_icon_with_title medium normal_icon '><div class=\"icon_holder \" style=\" \"><span data-icon-type=\"normal\"   style=\"\" class=\"qode_iwt_icon_holder q_font_awsome_icon fa-3x  \"><i class=\"qode_icon_font_awesome fa  qode_iwt_icon_element\" style=\"\" ><\/i><\/span><\/div><div class=\"icon_text_holder\" style=\"\"><div class=\"icon_text_inner\" style=\"\"><h5 class=\"icon_title\" style=\"\">Recycling Systems<\/h5><div class=\"separator small left\" style=\"height: 2px;width: 20px;margin-bottom: 15px;\"><\/div><p style=''>We have recycling systems at each of our locations to facilitate waste recycling as part of our commitment to sustainability.  <\/p><\/div><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-15efd0d elementor-section-full_width elementor-section-height-default elementor-section-height-default parallax_section_no qode_elementor_container_no\" data-id=\"15efd0d\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;animation&quot;:&quot;none&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-358d5e1\" data-id=\"358d5e1\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-690fa3a elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"690fa3a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-3a46f2d elementor-section-boxed elementor-section-height-default elementor-section-height-default parallax_section_no qode_elementor_container_no\" data-id=\"3a46f2d\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;animation&quot;:&quot;none&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-cafb388\" data-id=\"cafb388\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-091ac4e elementor-widget elementor-widget-image\" data-id=\"091ac4e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"322\" height=\"111\" src=\"https:\/\/www.bonitastay.com\/wp-content\/uploads\/2024\/01\/100.png\" class=\"attachment-large size-large wp-image-4814\" alt=\"\" srcset=\"https:\/\/www.bonitastay.com\/wp-content\/uploads\/2024\/01\/100.png 322w, https:\/\/www.bonitastay.com\/wp-content\/uploads\/2024\/01\/100-300x103.png 300w\" sizes=\"(max-width: 322px) 100vw, 322px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-e31fa3f\" data-id=\"e31fa3f\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-af5bf9d elementor-widget elementor-widget-image\" data-id=\"af5bf9d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"322\" height=\"111\" src=\"https:\/\/www.bonitastay.com\/wp-content\/uploads\/2023\/10\/Diseno-sin-titulo-9.png\" class=\"attachment-large size-large wp-image-4524\" alt=\"\" srcset=\"https:\/\/www.bonitastay.com\/wp-content\/uploads\/2023\/10\/Diseno-sin-titulo-9.png 322w, https:\/\/www.bonitastay.com\/wp-content\/uploads\/2023\/10\/Diseno-sin-titulo-9-300x103.png 300w\" sizes=\"(max-width: 322px) 100vw, 322px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-1f1604b\" data-id=\"1f1604b\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-cfaa41e elementor-widget elementor-widget-image\" data-id=\"cfaa41e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"331\" height=\"56\" src=\"https:\/\/www.bonitastay.com\/wp-content\/uploads\/2023\/05\/badge2.jpg\" class=\"attachment-large size-large wp-image-3155\" alt=\"\" srcset=\"https:\/\/www.bonitastay.com\/wp-content\/uploads\/2023\/05\/badge2.jpg 331w, https:\/\/www.bonitastay.com\/wp-content\/uploads\/2023\/05\/badge2-300x51.jpg 300w\" sizes=\"(max-width: 331px) 100vw, 331px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-b48daa4\" data-id=\"b48daa4\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3239c47 elementor-widget elementor-widget-image\" data-id=\"3239c47\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"262\" height=\"49\" src=\"https:\/\/www.bonitastay.com\/wp-content\/uploads\/2023\/05\/badge3.jpg\" class=\"attachment-large size-large wp-image-3156\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Best Price Book from our website and get the best price guaranteed. Long Stay 15% discount for stays of 14 nights or more. Adaptability We try to adapt by offering early check-in and late check-out. Best Price Book from our website and get the best&#8230;<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"full_width.php","meta":{"footnotes":""},"class_list":["post-3272","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Home - Bonita Stay<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.bonitastay.com\/en\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Home - Bonita Stay\" \/>\n<meta property=\"og:description\" content=\"Best Price Book from our website and get the best price guaranteed. Long Stay 15% discount for stays of 14 nights or more. Adaptability We try to adapt by offering early check-in and late check-out. Best Price Book from our website and get the best...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.bonitastay.com\/en\/\" \/>\n<meta property=\"og:site_name\" content=\"Bonita Stay\" \/>\n<meta property=\"article:modified_time\" content=\"2026-04-13T10:27:49+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.bonitastay.com\/wp-content\/uploads\/2023\/08\/2-1-355x229.png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"76 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.bonitastay.com\\\/en\\\/\",\"url\":\"https:\\\/\\\/www.bonitastay.com\\\/en\\\/\",\"name\":\"Home - Bonita Stay\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.bonitastay.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.bonitastay.com\\\/en\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.bonitastay.com\\\/en\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.bonitastay.com\\\/wp-content\\\/uploads\\\/2023\\\/08\\\/2-1-355x229.png\",\"datePublished\":\"2021-06-25T13:06:55+00:00\",\"dateModified\":\"2026-04-13T10:27:49+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.bonitastay.com\\\/en\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.bonitastay.com\\\/en\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.bonitastay.com\\\/en\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.bonitastay.com\\\/wp-content\\\/uploads\\\/2023\\\/08\\\/2-1-355x229.png\",\"contentUrl\":\"https:\\\/\\\/www.bonitastay.com\\\/wp-content\\\/uploads\\\/2023\\\/08\\\/2-1-355x229.png\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.bonitastay.com\\\/en\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/www.bonitastay.com\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Home\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.bonitastay.com\\\/#website\",\"url\":\"https:\\\/\\\/www.bonitastay.com\\\/\",\"name\":\"Bonita Stay\",\"description\":\"Casas Vacacionales\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.bonitastay.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.bonitastay.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.bonitastay.com\\\/#organization\",\"name\":\"Bonita Stay\",\"url\":\"https:\\\/\\\/www.bonitastay.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.bonitastay.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.bonitastay.com\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/main-logo_B.jpg\",\"contentUrl\":\"https:\\\/\\\/www.bonitastay.com\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/main-logo_B.jpg\",\"width\":169,\"height\":115,\"caption\":\"Bonita Stay\"},\"image\":{\"@id\":\"https:\\\/\\\/www.bonitastay.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Home - Bonita Stay","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.bonitastay.com\/en\/","og_locale":"en_US","og_type":"article","og_title":"Home - Bonita Stay","og_description":"Best Price Book from our website and get the best price guaranteed. Long Stay 15% discount for stays of 14 nights or more. Adaptability We try to adapt by offering early check-in and late check-out. Best Price Book from our website and get the best...","og_url":"https:\/\/www.bonitastay.com\/en\/","og_site_name":"Bonita Stay","article_modified_time":"2026-04-13T10:27:49+00:00","og_image":[{"url":"https:\/\/www.bonitastay.com\/wp-content\/uploads\/2023\/08\/2-1-355x229.png","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"76 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.bonitastay.com\/en\/","url":"https:\/\/www.bonitastay.com\/en\/","name":"Home - Bonita Stay","isPartOf":{"@id":"https:\/\/www.bonitastay.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.bonitastay.com\/en\/#primaryimage"},"image":{"@id":"https:\/\/www.bonitastay.com\/en\/#primaryimage"},"thumbnailUrl":"https:\/\/www.bonitastay.com\/wp-content\/uploads\/2023\/08\/2-1-355x229.png","datePublished":"2021-06-25T13:06:55+00:00","dateModified":"2026-04-13T10:27:49+00:00","breadcrumb":{"@id":"https:\/\/www.bonitastay.com\/en\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.bonitastay.com\/en\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.bonitastay.com\/en\/#primaryimage","url":"https:\/\/www.bonitastay.com\/wp-content\/uploads\/2023\/08\/2-1-355x229.png","contentUrl":"https:\/\/www.bonitastay.com\/wp-content\/uploads\/2023\/08\/2-1-355x229.png"},{"@type":"BreadcrumbList","@id":"https:\/\/www.bonitastay.com\/en\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.bonitastay.com\/en\/"},{"@type":"ListItem","position":2,"name":"Home"}]},{"@type":"WebSite","@id":"https:\/\/www.bonitastay.com\/#website","url":"https:\/\/www.bonitastay.com\/","name":"Bonita Stay","description":"Casas Vacacionales","publisher":{"@id":"https:\/\/www.bonitastay.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.bonitastay.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.bonitastay.com\/#organization","name":"Bonita Stay","url":"https:\/\/www.bonitastay.com\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.bonitastay.com\/#\/schema\/logo\/image\/","url":"https:\/\/www.bonitastay.com\/wp-content\/uploads\/2023\/05\/main-logo_B.jpg","contentUrl":"https:\/\/www.bonitastay.com\/wp-content\/uploads\/2023\/05\/main-logo_B.jpg","width":169,"height":115,"caption":"Bonita Stay"},"image":{"@id":"https:\/\/www.bonitastay.com\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.bonitastay.com\/en\/wp-json\/wp\/v2\/pages\/3272","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.bonitastay.com\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.bonitastay.com\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.bonitastay.com\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.bonitastay.com\/en\/wp-json\/wp\/v2\/comments?post=3272"}],"version-history":[{"count":151,"href":"https:\/\/www.bonitastay.com\/en\/wp-json\/wp\/v2\/pages\/3272\/revisions"}],"predecessor-version":[{"id":5925,"href":"https:\/\/www.bonitastay.com\/en\/wp-json\/wp\/v2\/pages\/3272\/revisions\/5925"}],"wp:attachment":[{"href":"https:\/\/www.bonitastay.com\/en\/wp-json\/wp\/v2\/media?parent=3272"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}